{"id":83679,"date":"2026-05-20T11:36:04","date_gmt":"2026-05-20T11:36:04","guid":{"rendered":"https:\/\/qimaterials.com\/?p=83679"},"modified":"2026-05-20T11:36:06","modified_gmt":"2026-05-20T11:36:06","slug":"qimc-reports-10-77-hydrogen-mud-gas-reading-at-west-advocate-five-stacked-level-readings-in-a-69-metre-methane-free-hydrogen-rich-interval-in-hole-ddh-26-03-west-advocate-nova-scotia","status":"publish","type":"post","link":"https:\/\/qimaterials.com\/fr\/qimc-reports-10-77-hydrogen-mud-gas-reading-at-west-advocate-five-stacked-level-readings-in-a-69-metre-methane-free-hydrogen-rich-interval-in-hole-ddh-26-03-west-advocate-nova-scotia\/","title":{"rendered":"QIMC signale une concentration de 10,771 TP3T d&#039;hydrog\u00e8ne dans les boues de forage \u00e0 West-Advocate \u2014 Cinq relev\u00e9s superpos\u00e9s de 1 TP3T dans un intervalle de 69 m\u00e8tres riche en hydrog\u00e8ne et exempt de m\u00e9thane, dans le forage DDH-26-03, \u00e0 West Advocate, en Nouvelle-\u00c9cosse."},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong><em>102 \u00e9chantillons de boue IsoJar pr\u00e9sentent un pic de 10,77% H\u2082 \u00e0 848 m, cinq mesures \u2265 5% H\u2082 dans l&#039;intervalle 779\u2013848 m, et trois mesures \u2265 7% dans un sous-intervalle de 33 m\u00e8tres (815\u2013848 m)\u00a0; les concentrations de m\u00e9thane et de CO\u2082 sont inf\u00e9rieures ou \u00e9gales au seuil de d\u00e9tection.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Montr\u00e9al (Qu\u00e9bec) \u2014 le 20 mai 2026 \u2014 <\/strong>Qu\u00e9bec Innovative Materials Corp. (CSE : QIMC) (OTCQB : QIMCF) (FSE : 7FJ) (\u201c QIMC \u201d ou la \u201c Soci\u00e9t\u00e9 \u201d) est heureuse d\u2019annoncer les r\u00e9sultats de l\u2019analyse des gaz de boue du forage DDH-26-03 dans le cadre de son projet d\u2019exploration d\u2019hydrog\u00e8ne naturel West-Advocate dans le comt\u00e9 de Cumberland, en Nouvelle-\u00c9cosse. <strong>QIMC-26-03 a renvoy\u00e9 les lectures de gaz H\u2082 les plus \u00e9lev\u00e9es jamais enregistr\u00e9es \u00e0 ce jour sur la propri\u00e9t\u00e9 West-Advocate.<\/strong> Ce forage repr\u00e9sente le premier test d&#039;extension lat\u00e9rale du syst\u00e8me H\u2082 r\u00e9alis\u00e9 par la Soci\u00e9t\u00e9. Il a \u00e9t\u00e9 effectu\u00e9 sur environ 2,5 kilom\u00e8tres le long du corridor structural Cobequid\u2013Chedabucto, \u00e0 partir des forages DDH-26-01 et DDH-26-02 pr\u00e9c\u00e9demment publi\u00e9s. L&#039;intersection de teneurs en H\u2082 nettement sup\u00e9rieures, \u00e0 2,5 km des emplacements de forage pr\u00e9c\u00e9dents, confirme l&#039;hypoth\u00e8se selon laquelle le syst\u00e8me hydrog\u00e8ne West-Advocate pourrait pr\u00e9senter une continuit\u00e9 lat\u00e9rale le long du corridor structural, plut\u00f4t que d&#039;\u00eatre confin\u00e9 \u00e0 une anomalie localis\u00e9e. Le forage a atteint une profondeur finale de 932 m\u00e8tres. Au total, 102 \u00e9chantillons de gaz de forage ont \u00e9t\u00e9 pr\u00e9lev\u00e9s \u00e0 l&#039;aide d&#039;un IsoJar sur l&#039;intervalle de 473 \u00e0 932 m\u00e8tres. L&#039;ensemble de donn\u00e9es renvoie une lecture maximale de 10,77% H\u2082 \u00e0 848 m \u2014 la valeur H\u2082 de gaz de boue la plus \u00e9lev\u00e9e enregistr\u00e9e \u00e0 ce jour sur la propri\u00e9t\u00e9 West-Advocate \u2014 ainsi que cinq lectures empil\u00e9es en pourcentage \u22655% H\u2082 dans un intervalle de 69 m\u00e8tres (5,10% \u00e0 779 m, 5,10% \u00e0 806 m, 8,87% \u00e0 815 m, 7,29% \u00e0 818 m et 10,77% \u00e0 848 m), trois lectures \u22657% dans un sous-intervalle plus \u00e9troit de 33 m\u00e8tres (815\u2013848 m) et une lecture \u00e9lev\u00e9e distincte de 3,42% \u00e0 668 m. Les cinq relev\u00e9s \u22655% H\u2082 sont tous situ\u00e9s dans un conglom\u00e9rat polymictique \u00e0 vacuoles contenant de la magn\u00e9tite et de la pyrrhotite. Les \u00e9chantillons de gaz pr\u00e9lev\u00e9s simultan\u00e9ment ont r\u00e9v\u00e9l\u00e9 des concentrations de m\u00e9thane (CH\u2084) et de dioxyde de carbone (CO\u2082) \u00e9gales ou inf\u00e9rieures au seuil de d\u00e9tection sur l&#039;ensemble de l&#039;intervalle d&#039;anomalie. La soci\u00e9t\u00e9 interpr\u00e8te cette signature gazeuse comme \u00e9tant caract\u00e9ristique d&#039;un syst\u00e8me \u00e0 hydrog\u00e8ne naturel et non typique des syst\u00e8mes de gaz d&#039;hydrocarbures thermog\u00e9niques conventionnels.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Points forts<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Niveaux de gaz H\u2082 les plus \u00e9lev\u00e9s jamais enregistr\u00e9s sur la propri\u00e9t\u00e9 West-Advocate\u00a0: <strong>10,77% H\u2082 \u00e0 848 m<\/strong>, Cinq mesures cons\u00e9cutives de H\u2082 \u2265 5% ont \u00e9t\u00e9 relev\u00e9es sur un intervalle de 69 m\u00e8tres (5,10% \u00e0 779 m, 5,10% \u00e0 806 m, 8,87% \u00e0 815 m, 7,29% \u00e0 818 m et 10,77% \u00e0 848 m), toutes incluses dans un conglom\u00e9rat polymictique fractur\u00e9 et vacuolaire. Une mesure suppl\u00e9mentaire, isol\u00e9e, de H\u2082 \u2265 3,42% a \u00e9t\u00e9 enregistr\u00e9e \u00e0 668 m.<\/li>\n\n\n\n<li>R\u00e9sultat du d\u00e9placement lat\u00e9ral : <strong>Le forage 3 a \u00e9t\u00e9 r\u00e9alis\u00e9 sur environ 2,5 km le long du corridor structural Cobequid\u2013Chedabucto \u00e0 partir des forages DDH-26-01 et DDH-26-02.<\/strong>, Les mesures ont r\u00e9v\u00e9l\u00e9 des concentrations d&#039;H\u2082 en pourcentage nettement sup\u00e9rieures \u00e0 la valeur maximale de l&#039;espace de t\u00eate d&#039;eau pr\u00e9c\u00e9demment enregistr\u00e9e pour le forage DDH-26-02 (8\u00a0249 ppmV \/ 0,821 TP3T \u00e0 434 m, le 19 mars 2026). Ce r\u00e9sultat confirme l&#039;hypoth\u00e8se selon laquelle le syst\u00e8me H\u2082 s&#039;\u00e9tend lat\u00e9ralement le long du corridor structural plut\u00f4t que de constituer une anomalie localis\u00e9e.<\/li>\n\n\n\n<li>Anomalie quasi continue de gaz de boue H\u2082 de 473 m \u00e0 932 m\u00a0: <strong>Sur 102 \u00e9chantillons de boue IsoJar, 26 valeurs d\u00e9passent 1% H\u2082, 7 d\u00e9passent 3%, 5 d\u00e9passent 5%, 3 d\u00e9passent 7% et 1 d\u00e9passe 10% en volume.<\/strong>. L\u2019\u00e9talonnage sur l\u2019ensemble des donn\u00e9es remplace l\u2019ensemble pr\u00e9c\u00e9dent de relev\u00e9s de d\u00e9tecteurs de terrain (qui comprenait de multiples \u00e9v\u00e9nements de d\u00e9passement de plage des capteurs) par des concentrations quantifi\u00e9es sur l\u2019ensemble du profil.<\/li>\n\n\n\n<li>Les \u00e9chantillons de gaz co-collect\u00e9s ont \u00e9t\u00e9 retourn\u00e9s <strong>CH\u2084 \u00e0 un niveau inf\u00e9rieur ou \u00e9gal au seuil de d\u00e9tection (inf\u00e9rieur \u00e0 0,1%) et CO2 \u00e0 la limite de d\u00e9tection<\/strong> dans l&#039;intervalle d&#039;anomalie \u2014 une signature gazeuse interpr\u00e9t\u00e9e par la Soci\u00e9t\u00e9 comme compatible avec un syst\u00e8me \u00e0 hydrog\u00e8ne naturel et non compatible avec un gaz thermog\u00e9nique.<\/li>\n\n\n\n<li>Les lectures de gaz de boue ont \u00e9t\u00e9 acquises pendant le forage \u00e0 l&#039;aide des instruments RKI Eagle 2 de la soci\u00e9t\u00e9 (capteur initial de la gamme LEL jusqu&#039;\u00e0 485 m, capteur de conductivit\u00e9 thermique am\u00e9lior\u00e9 0\u2013100% v\/v pour le reste du trou), avec des \u00e9chantillons d&#039;espace de t\u00eate IsoJar co-collect\u00e9s \u00e0 intervalles d&#039;environ 3 m.<\/li>\n\n\n\n<li>Trou termin\u00e9 \u00e0 <strong>932 m TD<\/strong> et environ 100% de r\u00e9cup\u00e9ration au total.<\/li>\n\n\n\n<li>La lithologie est coh\u00e9rente avec la cible <strong>architecture contr\u00f4l\u00e9e par d\u00e9fauts et fractures<\/strong> du mod\u00e8le d&#039;exploration R2G2\u2122 : siltites cataclastiques avec des gouges de failles de veines de boue r\u00e9p\u00e9t\u00e9es dans le trou sup\u00e9rieur, passant \u00e0 un conglom\u00e9rat polymictique \u00e0 vacuoles, contenant de la magn\u00e9tite et des sulfures en profondeur avec un style de fracture caract\u00e9ristique en \u201c jeton de poker \u201d perpendiculaire \u00e0 l&#039;axe de la carotte \u2014 le m\u00eame intervalle h\u00e9bergeant les lectures de H\u2082 au niveau du pourcentage.<\/li>\n\n\n\n<li>Toutes les lectures sur le terrain ont \u00e9t\u00e9 <strong>v\u00e9rifi\u00e9 ind\u00e9pendamment par le professeur Marc Richer-Lafl\u00e8che, P.Geo., de l&#039;INRS<\/strong>, qui a travaill\u00e9 sur le mod\u00e8le R2G2\u2122 et est l&#039;analyste scientifique ind\u00e9pendant du programme 2026 West-Advocate. Un commentaire ind\u00e9pendant figure ci-dessous.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Commentaire du PDG<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>John Karagiannidis, pr\u00e9sident-directeur g\u00e9n\u00e9ral de QIMC, a comment\u00e9\u00a0: <\/strong>\u201c<strong>DDH-26-03 <\/strong>Le forage DDH-26-03 a enregistr\u00e9 les plus fortes concentrations d&#039;hydrog\u00e8ne (H\u2082) jamais mesur\u00e9es par QIMC sur la propri\u00e9t\u00e9 West-Advocate, soit 10,771 TP3T \u00e0 848 m\u00e8tres de profondeur. Cinq concentrations, comprises entre 5,101 TP3T et 10,771 TP3T, ont \u00e9t\u00e9 relev\u00e9es sur une distance de 69 m\u00e8tres, et trois concentrations sup\u00e9rieures \u00e0 71 TP3T ont \u00e9t\u00e9 mesur\u00e9es sur une distance de seulement 33 m\u00e8tres. Ce forage, r\u00e9alis\u00e9 \u00e0 2,5 kilom\u00e8tres de distance des forages DDH-26-01 et DDH-26-02, constitue un prolongement lat\u00e9ral d\u00e9lib\u00e9r\u00e9 de 2,5 kilom\u00e8tres le long du corridor structural Cobequid\u2013Chedabucto. Les concentrations nettement plus \u00e9lev\u00e9es enregistr\u00e9es \u00e0 2,5 km des forages pr\u00e9c\u00e9dents sugg\u00e8rent qu&#039;il s&#039;agit d&#039;un syst\u00e8me hydrog\u00e9n\u00e9 \u00e9tendu plut\u00f4t que d&#039;une anomalie localis\u00e9e. Le pic \u00e0 deux chiffres est le chiffre principal, mais les r\u00e9sultats les plus importants, \u00e0 notre avis, sont la continuit\u00e9 lat\u00e9rale apparente observ\u00e9e sur une \u00e9chelle de 2,5 kilom\u00e8tres et la quasi-absence de m\u00e9thane et de CO2 sur l&#039;ensemble de l&#039;intervalle d&#039;anomalie, une signature gazeuse que nous interpr\u00e9tons comme \u00e9tant compatible avec un syst\u00e8me d&#039;hydrog\u00e8ne naturel plut\u00f4t qu&#039;avec une poche de gaz thermog\u00e9nique.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lectures de terrain s\u00e9lectionn\u00e9es de gaz de boue H\u2082 \u2014 QIMC DDH-26-03<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><td><strong>Profondeur (m)<\/strong><\/td><td><strong>Lecture H\u2082<\/strong><\/td><td><strong>Lithologie de l&#039;h\u00f4te<\/strong><\/td><td><strong>\u00c9tat \/ Instrument<\/strong><\/td><\/tr><\/thead><tbody><tr><td><strong>668<\/strong><\/td><td>3.42%<\/td><td>gr\u00e8s\/argilite interstratifi\u00e9s<\/td><td><em>Zone sur\u00e9lev\u00e9e discr\u00e8te au-dessus du groupe principal de niveau %<\/em><\/td><\/tr><tr><td><strong>779<\/strong><\/td><td><strong>5.10%<\/strong><\/td><td>Conglom\u00e9rat polymictique (sup\u00e9rieur)<\/td><td>Premi\u00e8re lecture \u22655% dans le cluster principal<\/td><\/tr><tr><td><strong>806<\/strong><\/td><td><strong>5.10%<\/strong><\/td><td>conglom\u00e9rat polymictique vuggy<\/td><td>&nbsp;<\/td><\/tr><tr><td><strong>815<\/strong><\/td><td><strong>8.87%<\/strong><\/td><td>conglom\u00e9rat polymictique vuggy<\/td><td>&nbsp;<\/td><\/tr><tr><td><strong>818<\/strong><\/td><td><strong>7.29%<\/strong><\/td><td>conglom\u00e9rat polymictique vuggy<\/td><td>&nbsp;<\/td><\/tr><tr><td><strong>830<\/strong><\/td><td>3.39%<\/td><td>conglom\u00e9rat polymictique vuggy<\/td><td><em>Lecture interm\u00e9diaire entre les pics de niveau %<\/em><\/td><\/tr><tr><td><strong>848<\/strong><\/td><td><strong>10.77%<\/strong><\/td><td>Conglom\u00e9rat polymictique vuggy \u00e0 pyrrhotite<\/td><td>Valeur maximale \u2014 lecture la plus \u00e9lev\u00e9e de gaz H\u2082 dans la boue enregistr\u00e9e \u00e0 ce jour sur la propri\u00e9t\u00e9 West-Advocate<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Le tableau pr\u00e9sente les sept lectures \u22653% H\u2082 de l&#039;ensemble de donn\u00e9es IsoJar de 102 \u00e9chantillons couvrant 473\u2013932 m. Les cinq lectures \u22655% H\u2082 (surlign\u00e9es) se situent dans un intervalle de 69 m\u00e8tres (779\u2013848 m) dans un conglom\u00e9rat polymictique \u00e0 vacuoles ; les deux lectures 3\u20135% (668 m et 830 m) sont des lectures interm\u00e9diaires \u00e9lev\u00e9es.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Figure 1 \u2014 Profil H\u2082 en fonction de la profondeur, QIMC DDH-26-03<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"480\" height=\"580\" src=\"https:\/\/qimaterials.com\/wp-content\/uploads\/2026\/05\/image.gif\" alt=\"\" class=\"wp-image-83680\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Figure 1. Profil de concentration en H\u2082 en fonction de la profondeur pour les 102 \u00e9chantillons de gaz de boue IsoJar du forage QIMC-26-03. Les \u00e9toiles rouges indiquent les cinq concentrations de H\u2082 sup\u00e9rieures ou \u00e9gales \u00e0 5% dans l&#039;intervalle principal de niveau % (779\u2013848 m)\u00a0: 5,10% \u00e0 779 m, 5,10% \u00e0 806 m, 8,87% \u00e0 815 m, 7,29% \u00e0 818 m et 10,77% \u00e0 848 m. Les losanges orange repr\u00e9sentent les deux concentrations de H\u2082 comprises entre 3% et 5% (3,42% \u00e0 668 m et 3,39% \u00e0 830 m). Les points bleus correspondent \u00e0 toutes les autres concentrations inf\u00e9rieures \u00e0 3%. La zone ombr\u00e9e d\u00e9limite l&#039;intervalle principal de niveau % contenu dans le conglom\u00e9rat polymictique \u00e0 cavit\u00e9s. Les lignes verticales pointill\u00e9es indiquent la LIE de H\u2082 dans l&#039;air (4% v\/v) et 10% v\/v.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Signature gazeuse \u2014 Conforme \u00e0 l&#039;hydrog\u00e8ne naturel \/ \u201c blanc \u201d<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sur les 102 \u00e9chantillons IsoJar pr\u00e9lev\u00e9s dans l&#039;intervalle 473\u2013932 m, les concentrations de m\u00e9thane (CH\u2084) et de dioxyde de carbone (CO\u2082) mesur\u00e9es simultan\u00e9ment \u00e9taient \u00e9gales ou inf\u00e9rieures au seuil de d\u00e9tection (maximum 0,11 TP3T). La pr\u00e9sence d&#039;hydrog\u00e8ne (H\u2082) \u00e0 des concentrations de l&#039;ordre du pour cent (jusqu&#039;\u00e0 10,771 TP3T en volume) dans un m\u00e9lange gazeux manifestement exempt de m\u00e9thane et de CO\u2082 est coh\u00e9rente avec une interpr\u00e9tation abiotique de l&#039;hydrog\u00e8ne, typique des r\u00e9actions eau-roche crustales telles que la serpentinisation des protolithes ultramafiques et la radiolyse de l&#039;eau de formation. Cette signature est atypique des syst\u00e8mes gaziers thermog\u00e9niques conventionnels, domin\u00e9s par le m\u00e9thane et les hydrocarbures l\u00e9gers associ\u00e9s. Cette signature distingue le syst\u00e8me gazier West-Advocate des gaz des syst\u00e8mes p\u00e9troliers conventionnels et conforte l&#039;interpr\u00e9tation structurale de la source qui sous-tend le mod\u00e8le de ciblage R2G2\u2122.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Contexte g\u00e9ologique<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le forage DDH-26-03 a \u00e9t\u00e9 r\u00e9alis\u00e9 au sein de la zone de faille de Cobequid\u2013Chedabucto (CCFZ), un corridor de cisaillement crustal de plus de 300 km h\u00e9rit\u00e9 de la suture du terrane Avalon\u2013Meguma et \u00e9l\u00e9ment structural central du mod\u00e8le d&#039;exploration de la g\u00e9ostructure de rift et de graben r\u00e9activ\u00e9e (R2G2\u2122) de la Soci\u00e9t\u00e9. Ce mod\u00e8le cible les syst\u00e8mes de failles et de fractures interpr\u00e9t\u00e9s comme des voies d&#039;advection pour la migration de l&#039;hydrog\u00e8ne d&#039;origine profonde et son pi\u00e9geage superficiel dans des faci\u00e8s s\u00e9dimentaires fractur\u00e9s et poreux.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le forage DDH-26-03, situ\u00e9 \u00e0 environ 2,5 kilom\u00e8tres le long du corridor structural \u00e0 partir des forages DDH-26-01 et DDH-26-02 pr\u00e9c\u00e9demment publi\u00e9s, constitue le premier test d&#039;extension lat\u00e9rale r\u00e9alis\u00e9 par la Soci\u00e9t\u00e9 sur le syst\u00e8me H\u2082 de West-Advocate. Sa g\u00e9om\u00e9trie visait \u00e0 d\u00e9terminer si la r\u00e9ponse H\u2082-gaz de forage observ\u00e9e dans les forages 1 et 2 s&#039;\u00e9tend lat\u00e9ralement le long du corridor ou si elle est confin\u00e9e \u00e0 un compartiment structural localis\u00e9. L&#039;intersection, dans le forage DDH-26-03, de concentrations de H\u2082 atteignant 10,771 TP3T, nettement sup\u00e9rieures aux concentrations mesur\u00e9es dans l&#039;espace de t\u00eate du forage 2 (DDH-26-02) (0,821 TP3T \u00e0 434 m, rapport\u00e9es le 19 mars 2026), conforte l&#039;interpr\u00e9tation selon laquelle West-Advocate pourrait repr\u00e9senter un syst\u00e8me d&#039;hydrog\u00e8ne naturel contr\u00f4l\u00e9 par la structure, pr\u00e9sentant une continuit\u00e9 lat\u00e9rale potentielle \u00e0 l&#039;\u00e9chelle de 2,5 km, plut\u00f4t qu&#039;une anomalie localis\u00e9e. Le forage 3 \u00e9tend \u00e9galement la profondeur de p\u00e9n\u00e9tration de la propri\u00e9t\u00e9 d&#039;environ 220 m\u00e8tres par rapport au DDH-26-01.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&#039;analyse lithologique du forage DDH-26-03 confirme l&#039;hypoth\u00e8se de ciblage. La section sup\u00e9rieure (3\u201349,7 m) est un siltstone \u00e0 grain fin perturb\u00e9 par des failles, pr\u00e9sentant des gouges de failles \u00e0 joints de boue et des intervalles br\u00e9chiques. L&#039;intervalle interm\u00e9diaire est un ensemble stratifi\u00e9 de siltstone, d&#039;argilite et de gr\u00e8s, ponctu\u00e9 de br\u00e8ches de failles cisaill\u00e9es, incluant une mesure ponctuelle de H\u2082 de 3,421 TP3T \u00e0 668 m au-dessus du groupe principal de niveaux 1 TP3T. De 780 m environ jusqu&#039;\u00e0 la profondeur totale, le forage \u00e9volue vers un conglom\u00e9rat polymictique magn\u00e9tique \u00e0 pyrrhotite, pr\u00e9sentant une texture vacuolaire g\u00e9n\u00e9ralis\u00e9e et une fracturation en \u201c jetons \u201d perpendiculaire \u00e0 l&#039;axe de la carotte \u2013 une fabrique compatible avec une porosit\u00e9 secondaire renforc\u00e9e par la structure. Les cinq mesures de H\u2082 \u2265 5% (5,10% \u00e0 779 m, 5,10% \u00e0 806 m, 8,87% \u00e0 815 m, 7,29% \u00e0 818 m et 10,77% \u00e0 848 m) ont \u00e9t\u00e9 enregistr\u00e9es au sein de ce conglom\u00e9rat, regroup\u00e9es dans un intervalle de 69 m\u00e8tres que la Soci\u00e9t\u00e9 interpr\u00e8te comme un intervalle hydrog\u00e9n\u00e9. Trois de ces mesures (815, 818 et 848 m) sont regroup\u00e9es dans un sous-intervalle plus restreint de 33 m\u00e8tres, toutes affichant des valeurs \u2265 7%.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Commentaire scientifique ind\u00e9pendant \u2014 Pr Marc Richer-Lafl\u00e8che, P.Geo. (INRS)<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Donn\u00e9es provenant de <strong>trou de forage DDH\u201126\u201103<\/strong> Ces r\u00e9sultats fournissent des informations cl\u00e9s pour l&#039;exploration de l&#039;hydrog\u00e8ne naturel dans la r\u00e9gion de West Advocate (Nouvelle-\u00c9cosse). Le forage r\u00e9v\u00e8le des concentrations \u00e9lev\u00e9es en H\u2082 (ppmV) dans l&#039;eau et dans l&#039;espace de t\u00eate de la boue de forage, avec des valeurs qui augmentent avec la profondeur et en direction des anomalies magn\u00e9tiques cartographi\u00e9es lors du lev\u00e9 a\u00e9romagn\u00e9tique des hautes terres de Cobequid r\u00e9alis\u00e9 par le gouvernement de la Nouvelle-\u00c9cosse. Les anomalies d&#039;hydrog\u00e8ne les plus importantes se trouvent dans les conglom\u00e9rats diversement fractur\u00e9s du groupe Horton (<strong>Fig. 2b<\/strong>Ces unit\u00e9s pr\u00e9sentent une susceptibilit\u00e9 magn\u00e9tique \u00e9lev\u00e9e, compatible avec la pr\u00e9sence de fragments de magn\u00e9tite et, localement, de pyrrhotite au sein de la matrice conglom\u00e9ratique fractur\u00e9e. Spatialement, une corr\u00e9lation claire se d\u00e9gage entre les conglom\u00e9rats riches en magn\u00e9tite et les concentrations en H\u2082 les plus \u00e9lev\u00e9es mesur\u00e9es. <strong>DDH\u201126\u201103<\/strong> (<strong>Fig. 2c<\/strong>Cette association pourrait refl\u00e9ter un lien g\u00e9n\u00e9tique entre l&#039;hydrog\u00e8ne et la magn\u00e9tite, potentiellement par le biais de r\u00e9actions redox impliquant des phases min\u00e9rales Fe(II)\u2013Fe(III), et\/ou une connexion \u00e0 des sources magmatiques profondes responsables du m\u00e9tasomatisme observ\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Le contexte g\u00e9ologique de ce secteur des hautes terres de Cobequid sugg\u00e8re une interaction complexe entre d&#039;importants couloirs de d\u00e9formation (la zone de faille de Cobequid-Chedabucto, CCFZ), des roches s\u00e9dimentaires perm\u00e9ables, comp\u00e9tentes et fractur\u00e9es, et des conglom\u00e9rats \u00e0 magn\u00e9tite et sulfures au sein d&#039;un environnement s\u00e9dimento-plutonique. L&#039;ensemble de ces caract\u00e9ristiques laisse entrevoir la possibilit\u00e9 d&#039;un syst\u00e8me hydrothermal fossile pr\u00e9sentant des affinit\u00e9s avec une min\u00e9ralisation de type IOCG associ\u00e9e \u00e0 une intrusion. Il est \u00e0 noter que plusieurs syst\u00e8mes de type IOCG du Carbonif\u00e8re sup\u00e9rieur sont d\u00e9j\u00e0 identifi\u00e9s le long de la CCFZ en Nouvelle-\u00c9cosse, notamment les gisements de fer de Londonderry et de South Manchester, ainsi que les gisements de Copper Lake et de Mount Thom (Cu-Au-Co) (Belperio, 2007\u00a0; MacHattie et O&#039;Reilly, 2008).<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"553\" height=\"421\" src=\"https:\/\/qimaterials.com\/wp-content\/uploads\/2026\/05\/image.jpeg\" alt=\"\" class=\"wp-image-83681\" srcset=\"https:\/\/qimaterials.com\/wp-content\/uploads\/2026\/05\/image.jpeg 553w, https:\/\/qimaterials.com\/wp-content\/uploads\/2026\/05\/image-300x228.jpeg 300w\" sizes=\"(max-width: 553px) 100vw, 553px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Figure 2. <\/strong>(<strong>A<\/strong>) Variabilit\u00e9 des concentrations de H\u2082 (ppmV) mesur\u00e9es dans les \u00e9chantillons d&#039;espace de t\u00eate d&#039;eau provenant du forage DDH-26-03. (<strong>B<\/strong>) Indice de qualit\u00e9 de la roche (RQD, %) mesur\u00e9 le long de la carotte de forage. (<strong>C<\/strong>) Valeurs de susceptibilit\u00e9 magn\u00e9tique (SI \u00d7 10\u207b\u00b3) obtenues \u00e0 partir de mesures syst\u00e9matiques sur les carottes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Prochaines \u00e9tapes<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Forage 2 (DDH-26-02) approfondi \u00e0 environ 900 m \u2014 actif<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Suite \u00e0 la d\u00e9monstration de concentrations d&#039;hydrog\u00e8ne (H\u2082) proches de 806 \u00e0 848 m dans la fen\u00eatre de profondeur du forage DDH-26-03, la Soci\u00e9t\u00e9 a remis en service l&#039;appareil de forage sur le forage DDH-26-02, dont les travaux avaient \u00e9t\u00e9 interrompus \u00e0 environ 500 m en raison du d\u00e9gel printanier. La Soci\u00e9t\u00e9 avait alors constat\u00e9 que des concentrations \u00e9lev\u00e9es d&#039;hydrog\u00e8ne (H\u2082) en fond de forage indiquaient que le syst\u00e8me restait ouvert en profondeur. Le forage 2 est actuellement en cours d&#039;approfondissement jusqu&#039;\u00e0 une profondeur finale pr\u00e9vue d&#039;environ 900 m\u00e8tres afin de tester la m\u00eame fen\u00eatre de profondeur qui avait permis d&#039;obtenir les concentrations proches de 806 \u00e0 848 m dans le forage QIMC-26-03, au niveau du collet du forage 2.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>L&#039;\u00e9chantillonnage des gaz de forage sur la section approfondie du forage 2 a d\u00e9j\u00e0 commenc\u00e9.<\/strong>, La soci\u00e9t\u00e9 a proc\u00e9d\u00e9 \u00e0 l&#039;analyse de la section approfondie du forage 2 en utilisant le m\u00eame instrument RKI Eagle 2 (TCD, 0\u2013100% v\/v H\u2082) am\u00e9lior\u00e9, un \u00e9chantillonnage de boue IsoJar \u00e0 intervalles d&#039;environ 3 m\u00e8tres et les protocoles d&#039;assurance et de contr\u00f4le qualit\u00e9 sur le terrain appliqu\u00e9s au forage DDH26-03. Elle pr\u00e9voit de publier les r\u00e9sultats dans un prochain communiqu\u00e9 de presse une fois le forage et l&#039;\u00e9chantillonnage termin\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Bennett Hill (East Advocate) \u2014 Trous 4 et 5 ensuite, \u00e0 environ 12,5 km le long de la zone de faille de Cobequid<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les deux prochains forages du programme d&#039;exploration 2026 de la Soci\u00e9t\u00e9 \u2014 d\u00e9sign\u00e9s ici sous les noms de DDH-26-04 et DDH-26-05, et constituant les deux premiers forages du programme de trois forages de la phase 1 de Bennett Hill, autoris\u00e9 s\u00e9par\u00e9ment \u2014 seront r\u00e9alis\u00e9s sur le projet Bennett Hill, dans le secteur d&#039;East Advocate, situ\u00e9 \u00e0 environ 12,5 km le long de la zone de faille de Cobequid, \u00e0 partir du groupe de forages QIMC-26-01\/-02\/-03 \u00e0 West-Advocate. Les cibles de forage \u00e0 Bennett Hill ont \u00e9t\u00e9 d\u00e9finies gr\u00e2ce \u00e0 la campagne de gaz du sol men\u00e9e par la Soci\u00e9t\u00e9 en 2025, qui a mis en \u00e9vidence une ligne anormale quasi continue de 4 km le long de Bennett Hill Road, avec une concentration moyenne en H\u2082 de 623 ppm et un pic de 2\u00a0247 ppm (47 \u00e9chantillons\u00a0; r\u00e9sultats du 3 septembre 2025).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Parall\u00e8lement, un programme \u00e9largi de surveillance des gaz du sol a d\u00e9but\u00e9 dans l&#039;extension de la zone de Bennett Hill.<\/strong>, S\u2019appuyant sur la m\u00e9thodologie et les r\u00e9sultats de la campagne de 2025, le programme actuel \u00e9tend la zone prospect\u00e9e le long du corridor de la faille de Cobequid et vise \u00e0 affiner la d\u00e9finition des cibles de forage. Les concentrations d\u2019hydrog\u00e8ne (H\u2082) mesur\u00e9es en profondeur dans le forage QIMC-26-03, au sein du contexte structural pr\u00e9dit ind\u00e9pendamment par la cartographie des gaz du sol en surface et la cartographie structurale, sont interpr\u00e9t\u00e9es par la Soci\u00e9t\u00e9 comme une confirmation, \u00e0 l\u2019\u00e9chelle du terrain, de la relation et de la reproductibilit\u00e9 entre les anomalies de gaz du sol en surface et les accumulations d\u2019hydrog\u00e8ne en subsurface. Ces r\u00e9sultats constituent un appui pr\u00e9liminaire \u00e0 la m\u00e9thode de ciblage appliqu\u00e9e \u00e0 Bennett Hill.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Perspectives du programme au-del\u00e0 de Bennett Hill<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Suite \u00e0 l&#039;approfondissement des forages DDH-26-02, DDH-26-04 et DDH-26-05 \u00e0 Bennett Hill, et aux analyses INRS du forage QIMC-26-03, la Soci\u00e9t\u00e9 int\u00e9grera l&#039;ensemble des donn\u00e9es combin\u00e9es (gaz du sol en surface, cartographie structurale, trois forages \u00e0 West-Advocate et les deux forages \u00e0 venir \u00e0 Bennett Hill) afin de prioriser les cibles de forage ult\u00e9rieures. QIMC poursuit les d\u00e9marches d&#039;obtention des permis et l&#039;examen technique pour les secteurs de Little Forks et de Spring Hill, qui constituent la prochaine priorit\u00e9 de sa strat\u00e9gie d&#039;exploration d&#039;hydrog\u00e8ne naturel \u00e0 l&#039;\u00e9chelle du district en Nouvelle-\u00c9cosse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Comit\u00e9 d&#039;engagement communautaire et de liaison communautaire<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">QIMC remercie sinc\u00e8rement les r\u00e9sidents et les membres de la communaut\u00e9 qui ont particip\u00e9 \u00e0 la journ\u00e9e portes ouvertes organis\u00e9e \u00e0 West Advocate le 11 mai 2026, qui a connu un vif succ\u00e8s, et prend note des \u00e9changes constructifs et des commentaires re\u00e7us \u00e0 cette occasion. L&#039;entreprise appr\u00e9cie le temps, les points de vue et les questions partag\u00e9s par les participants.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans le cadre de sa strat\u00e9gie d&#039;engagement communautaire, d\u00e9j\u00e0 annonc\u00e9e, QIMC met sur pied un comit\u00e9 de liaison communautaire. Ce comit\u00e9 offrira un cadre consultatif structur\u00e9 favorisant une communication transparente et bilat\u00e9rale, la r\u00e9troaction de la communaut\u00e9 et un dialogue constructif concernant les activit\u00e9s d&#039;exploration de la Soci\u00e9t\u00e9 dans la r\u00e9gion. Les points de vue exprim\u00e9s par les membres de la communaut\u00e9 lors de la journ\u00e9e portes ouvertes du 11 mai contribueront \u00e0 d\u00e9finir la structure, la composition et les priorit\u00e9s op\u00e9rationnelles du comit\u00e9. QIMC demeure d\u00e9termin\u00e9e \u00e0 maintenir une communication transparente et bilat\u00e9rale avec la communaut\u00e9 d&#039;Advocate, tandis que les travaux d&#039;exploration se poursuivent \u00e0 West Advocate, \u00e0 Bennett Hill et dans le cadre du programme d&#039;hydrog\u00e8ne naturel de la Soci\u00e9t\u00e9 \u00e0 l&#039;\u00e9chelle du district en Nouvelle-\u00c9cosse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c0 propos de QIMC<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Qu\u00e9bec Mat\u00e9riaux Innovatifs Corp. est une soci\u00e9t\u00e9 nord-am\u00e9ricaine d&#039;exploration et de d\u00e9veloppement qui fait progresser un portefeuille de projets d&#039;hydrog\u00e8ne naturel et de min\u00e9raux critiques. La soci\u00e9t\u00e9 d\u00e9ploie son mod\u00e8le d&#039;exploration d&#039;hydrog\u00e8ne \u00e0 l&#039;\u00e9chelle d&#039;un district au Qu\u00e9bec, en Ontario, en Nouvelle-\u00c9cosse et au Minnesota, en tirant parti de son cadre exclusif R2G2\u2122.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">QIMC s&#039;engage en faveur d&#039;une exploration responsable, d&#039;une innovation technique et d&#039;un d\u00e9veloppement durable, dans le but de soutenir les initiatives en mati\u00e8re d&#039;\u00e9nergie propre et de d\u00e9carbonation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>F<\/strong><strong>ou Informations compl\u00e9mentaires\u00a0:<\/strong><br><strong>QU\u00c9BEC MAT\u00c9RIAUX INNOVANTS CORP.<\/strong><br>John Karagiannidis<br>Pr\u00e9sident et chef de la direction<br>E-mail: <a href=\"mailto:info@qimaterials.com\">info@qimaterials.com<\/a><br>T\u00e9l. : +1 514-726-7058<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Clause de non-responsabilit\u00e9<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Ni la Bourse canadienne des valeurs mobili\u00e8res ni son fournisseur de services de r\u00e9glementation n&#039;assument la responsabilit\u00e9 de l&#039;exactitude ou de l&#039;exhaustivit\u00e9 du pr\u00e9sent communiqu\u00e9.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>D\u00e9clarations prospectives<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Ce communiqu\u00e9 de presse contient des \u201c informations prospectives \u201d et des \u201c \u00e9nonc\u00e9s prospectifs \u201d au sens de la l\u00e9gislation canadienne applicable en mati\u00e8re de valeurs mobili\u00e8res. Les \u00e9nonc\u00e9s prospectifs comprennent, sans s\u2019y limiter, des \u00e9nonc\u00e9s concernant l\u2019interpr\u00e9tation des r\u00e9sultats de forage, le calendrier et les r\u00e9sultats pr\u00e9vus des analyses de laboratoire, le mod\u00e8le g\u00e9ologique sous-jacent au projet West-Advocate, l\u2019origine pr\u00e9sum\u00e9e (abiog\u00e8ne\/thermog\u00e8ne) du gaz mentionn\u00e9 dans le pr\u00e9sent document, la continuit\u00e9 lat\u00e9rale pr\u00e9sum\u00e9e du syst\u00e8me H\u2082 \u00e0 travers le corridor structural, les plans de forage suppl\u00e9mentaires et la strat\u00e9gie d\u2019exploration et d\u2019affaires de la Soci\u00e9t\u00e9. Ces \u00e9nonc\u00e9s reposent sur des hypoth\u00e8ses et des attentes que QIMC juge raisonnables \u00e0 la date des pr\u00e9sentes, mais ils sont assujettis \u00e0 des risques et incertitudes connus et inconnus \u2014 y compris, sans toutefois s\u2019y limiter, la volatilit\u00e9 des prix des mati\u00e8res premi\u00e8res, le risque d\u2019exploration, le risque que les r\u00e9sultats de laboratoire ne confirment pas les relev\u00e9s de terrain, le risque r\u00e9glementaire et d\u2019obtention de permis, le risque de financement et les conditions g\u00e9n\u00e9rales du march\u00e9 et d\u2019exploitation \u2014 qui pourraient faire en sorte que les r\u00e9sultats r\u00e9els diff\u00e8rent sensiblement. Les lecteurs sont pri\u00e9s de ne pas se fier ind\u00fbment aux \u00e9nonc\u00e9s prospectifs. La Soci\u00e9t\u00e9 ne s&#039;engage \u00e0 aucune obligation de mise \u00e0 jour des d\u00e9clarations prospectives, sauf si la loi l&#039;exige.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Les mesures de gaz de forage pr\u00e9sent\u00e9es dans ce communiqu\u00e9 sont bas\u00e9es sur des \u00e9chantillons d&#039;espace de t\u00eate pr\u00e9lev\u00e9s simultan\u00e9ment \u00e0 l&#039;aide d&#039;un IsoJar, \u00e0 intervalles d&#039;environ 3 m\u00e8tres, lors du forage du puits DDH-26-03. Ces \u00e9chantillons ont ensuite \u00e9t\u00e9 \u00e9talonn\u00e9s par le professeur Marc Richer-Lafl\u00e8che, g\u00e9ologue professionnel de l&#039;INRS, \u00e0 l&#039;aide d&#039;un instrument de r\u00e9f\u00e9rence de laboratoire de plus haute pr\u00e9cision. L&#039;\u00e9talonnage complet des donn\u00e9es a \u00e9t\u00e9 appliqu\u00e9 aux 102 \u00e9chantillons IsoJar et remplace les mesures in situ pr\u00e9c\u00e9dentes (qui comportaient plusieurs d\u00e9passements de plage de d\u00e9tection) pour les valeurs pr\u00e9sent\u00e9es dans ce communiqu\u00e9. Ces mesures indiquent la pr\u00e9sence d&#039;intervalles gaz\u00e9if\u00e8res rencontr\u00e9s lors du forage, mais ne doivent pas \u00eatre consid\u00e9r\u00e9es comme repr\u00e9sentatives de la composition du gaz du r\u00e9servoir in situ, des volumes de gaz en place, du potentiel d&#039;\u00e9coulement soutenu ou des ressources en hydrog\u00e8ne commercialisables. Aucun essai d&#039;\u00e9coulement n&#039;a \u00e9t\u00e9 r\u00e9alis\u00e9. Les r\u00e9f\u00e9rences aux \u201c\u00a0concentrations record de H\u2082 dans les gaz de forage \u00e0 ce jour\u00a0\u201d et au \u201c\u00a0pic de 10,771\u00a0TP3T H\u2082\u00a0\u201d se r\u00e9f\u00e8rent aux donn\u00e9es historiques de la Soci\u00e9t\u00e9 sur la propri\u00e9t\u00e9 West-Advocate et n\u2019impliquent aucune comparaison avec un projet ou des donn\u00e9es d\u2019un tiers. Toutes les valeurs rapport\u00e9es sont \u00e9talonn\u00e9es INRS par le professeur Marc Richer-Lafl\u00e8che, g\u00e9ologue professionnel, \u00e0 l\u2019aide d\u2019une r\u00e9f\u00e9rence de laboratoire de plus haute pr\u00e9cision. Les valeurs de H\u2082 correspondent aux concentrations de gaz de forage sur le terrain et sont indicatives des intervalles gaz\u00e9if\u00e8res rencontr\u00e9s lors du forage\u00a0; elles ne sont pas \u00e9quivalentes \u00e0 la composition du r\u00e9servoir dans les conditions in situ. La Soci\u00e9t\u00e9 n\u2019a r\u00e9alis\u00e9 aucune \u00e9valuation \u00e9conomique, estimation des ressources ni \u00e9valuation des flux commerciaux pour le projet West-Advocate.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Les mesures des gaz de forage ont \u00e9t\u00e9 effectu\u00e9es au niveau de la conduite de retour du pi\u00e8ge \u00e0 gaz de la plateforme \u00e0 l&#039;aide de d\u00e9tecteurs multigaz portables Eagle 2 et Ga5000 de RKI Instruments, associ\u00e9s \u00e0 des \u00e9chantillons d&#039;espace de t\u00eate IsoJar pr\u00e9lev\u00e9s \u00e0 intervalles d&#039;environ 3 m\u00e8tres sur l&#039;intervalle de 473 \u00e0 932 m. Le d\u00e9tecteur initial d\u00e9ploy\u00e9 au niveau du pieu \u00e9tait \u00e9quip\u00e9 d&#039;un capteur H\u2082 de la gamme LIE (r\u00e9ponse pleine \u00e9chelle calibr\u00e9e \u00e9quivalente \u00e0 environ 41 TP3T H\u2082 en volume \/ 1001 TP3T LIE).<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>L&#039;\u00e9talonnage est r\u00e9alis\u00e9 \u00e0 l&#039;aide de sachets en aluminium remplis de gaz \u00e9talons certifi\u00e9s, car cette m\u00e9thode reproduit fid\u00e8lement les conditions d&#039;\u00e9chantillonnage utilis\u00e9es lors des mesures de routine. En introduisant le gaz d&#039;\u00e9talonnage par le m\u00eame circuit de recirculation que nos \u00e9chantillons de terrain, nous nous assurons que l&#039;instrument prenne en compte tout effet li\u00e9 au d\u00e9bit, \u00e0 la tubulure, au mat\u00e9riau du sachet ou \u00e0 la dilution interne. Cette approche permet un \u00e9talonnage plus repr\u00e9sentatif et fiable, am\u00e9liore la pr\u00e9cision quantitative et garantit une r\u00e9ponse coh\u00e9rente du GA5000 aux gaz d&#039;\u00e9talonnage comme aux \u00e9chantillons r\u00e9els. Des tests de fonctionnement ont \u00e9t\u00e9 effectu\u00e9s et compil\u00e9s pour chaque poste de travail au sein du laboratoire mobile. Des blancs analytiques (air ambiant) ont \u00e9t\u00e9 r\u00e9alis\u00e9s afin de v\u00e9rifier le bon fonctionnement des d\u00e9tecteurs.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u00c0 485 m, ce capteur a enregistr\u00e9 le premier d\u00e9passement de plage de mesure prolong\u00e9 du forage. Afin de pr\u00e9server l&#039;int\u00e9grit\u00e9 des donn\u00e9es quantitatives pour le reste du forage, la soci\u00e9t\u00e9 a acquis et d\u00e9ploy\u00e9 une seconde unit\u00e9 Eagle 2 \u00e9quip\u00e9e d&#039;un capteur de conductivit\u00e9 thermique (TCD) H\u2082 \u00e9talonn\u00e9 de 0 \u00e0 1001 TP3T en volume. Cette unit\u00e9 a \u00e9t\u00e9 utilis\u00e9e pour le reste du forage DDH-26-03 conform\u00e9ment aux protocoles d&#039;assurance et de contr\u00f4le qualit\u00e9 standard sur le terrain, incluant un \u00e9talonnage avant prise de poste avec un gaz t\u00e9moin H\u2082-dans-N\u2082 certifi\u00e9. Des \u00e9chantillons de boue IsoJar ont \u00e9t\u00e9 pr\u00e9lev\u00e9s pour v\u00e9rification en laboratoire \u00e0 l&#039;INRS.<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>102 IsoJar mud samples return peak 10.77% H\u2082 at 848 m, five readings \u22655% H\u2082 in the 779\u2013848 m interval, three readings \u22657% in a 33-metre sub-interval (815\u2013848 m); methane and CO2 at or below detection Montr\u00e9al, Qu\u00e9bec \u2014 May 20, 2026 \u2014 Qu\u00e9bec Innovative Materials Corp. (CSE: QIMC) (OTCQB: QIMCF) (FSE: 7FJ) (\u201cQIMC\u201d or [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","iawp_total_views":298,"footnotes":""},"categories":[10,11],"tags":[],"class_list":["post-83679","post","type-post","status-publish","format-standard","hentry","category-industry-news","category-press-releases"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>QIMC Reports 10.77% Hydrogen Mud-Gas Reading at West-Advocate \u2014 Five Stacked %-Level Readings in a 69-Metre Methane-Free Hydrogen-Rich Interval in Hole DDH-26-03, West Advocate, Nova Scotia - QIMC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/qimaterials.com\/fr\/qimc-reports-10-77-hydrogen-mud-gas-reading-at-west-advocate-five-stacked-level-readings-in-a-69-metre-methane-free-hydrogen-rich-interval-in-hole-ddh-26-03-west-advocate-nova-scotia\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"QIMC Reports 10.77% Hydrogen Mud-Gas Reading at West-Advocate \u2014 Five Stacked %-Level Readings in a 69-Metre Methane-Free Hydrogen-Rich Interval in Hole DDH-26-03, West Advocate, Nova Scotia - QIMC\" \/>\n<meta property=\"og:description\" content=\"102 IsoJar mud samples return peak 10.77% H\u2082 at 848 m, five readings \u22655% H\u2082 in the 779\u2013848 m interval, three readings \u22657% in a 33-metre sub-interval (815\u2013848 m); methane and CO2 at or below detection Montr\u00e9al, Qu\u00e9bec \u2014 May 20, 2026 \u2014 Qu\u00e9bec Innovative Materials Corp. (CSE: QIMC) (OTCQB: QIMCF) (FSE: 7FJ) (\u201cQIMC\u201d or [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/qimaterials.com\/fr\/qimc-reports-10-77-hydrogen-mud-gas-reading-at-west-advocate-five-stacked-level-readings-in-a-69-metre-methane-free-hydrogen-rich-interval-in-hole-ddh-26-03-west-advocate-nova-scotia\/\" \/>\n<meta property=\"og:site_name\" content=\"QIMC\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-20T11:36:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-20T11:36:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/qimaterials.com\/wp-content\/uploads\/2026\/05\/image.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"580\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"author\" content=\"OPS OPS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"OPS OPS\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/qimaterials.com\\\/qimc-reports-10-77-hydrogen-mud-gas-reading-at-west-advocate-five-stacked-level-readings-in-a-69-metre-methane-free-hydrogen-rich-interval-in-hole-ddh-26-03-west-advocate-nova-scotia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/qimaterials.com\\\/qimc-reports-10-77-hydrogen-mud-gas-reading-at-west-advocate-five-stacked-level-readings-in-a-69-metre-methane-free-hydrogen-rich-interval-in-hole-ddh-26-03-west-advocate-nova-scotia\\\/\"},\"author\":{\"name\":\"OPS OPS\",\"@id\":\"https:\\\/\\\/qimaterials.com\\\/#\\\/schema\\\/person\\\/4b0b8cdace5e0ece1df885772763f8f1\"},\"headline\":\"QIMC Reports 10.77% Hydrogen Mud-Gas Reading at West-Advocate \u2014 Five Stacked %-Level Readings in a 69-Metre Methane-Free Hydrogen-Rich Interval in Hole DDH-26-03, West Advocate, Nova Scotia\",\"datePublished\":\"2026-05-20T11:36:04+00:00\",\"dateModified\":\"2026-05-20T11:36:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/qimaterials.com\\\/qimc-reports-10-77-hydrogen-mud-gas-reading-at-west-advocate-five-stacked-level-readings-in-a-69-metre-methane-free-hydrogen-rich-interval-in-hole-ddh-26-03-west-advocate-nova-scotia\\\/\"},\"wordCount\":3108,\"image\":{\"@id\":\"https:\\\/\\\/qimaterials.com\\\/qimc-reports-10-77-hydrogen-mud-gas-reading-at-west-advocate-five-stacked-level-readings-in-a-69-metre-methane-free-hydrogen-rich-interval-in-hole-ddh-26-03-west-advocate-nova-scotia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/qimaterials.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/image.gif\",\"articleSection\":[\"Industry News\",\"Press Releases\"],\"inLanguage\":\"fr-CA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/qimaterials.com\\\/qimc-reports-10-77-hydrogen-mud-gas-reading-at-west-advocate-five-stacked-level-readings-in-a-69-metre-methane-free-hydrogen-rich-interval-in-hole-ddh-26-03-west-advocate-nova-scotia\\\/\",\"url\":\"https:\\\/\\\/qimaterials.com\\\/qimc-reports-10-77-hydrogen-mud-gas-reading-at-west-advocate-five-stacked-level-readings-in-a-69-metre-methane-free-hydrogen-rich-interval-in-hole-ddh-26-03-west-advocate-nova-scotia\\\/\",\"name\":\"QIMC Reports 10.77% Hydrogen Mud-Gas Reading at West-Advocate \u2014 Five Stacked %-Level Readings in a 69-Metre Methane-Free Hydrogen-Rich Interval in Hole DDH-26-03, West Advocate, Nova Scotia - QIMC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/qimaterials.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/qimaterials.com\\\/qimc-reports-10-77-hydrogen-mud-gas-reading-at-west-advocate-five-stacked-level-readings-in-a-69-metre-methane-free-hydrogen-rich-interval-in-hole-ddh-26-03-west-advocate-nova-scotia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/qimaterials.com\\\/qimc-reports-10-77-hydrogen-mud-gas-reading-at-west-advocate-five-stacked-level-readings-in-a-69-metre-methane-free-hydrogen-rich-interval-in-hole-ddh-26-03-west-advocate-nova-scotia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/qimaterials.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/image.gif\",\"datePublished\":\"2026-05-20T11:36:04+00:00\",\"dateModified\":\"2026-05-20T11:36:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/qimaterials.com\\\/#\\\/schema\\\/person\\\/4b0b8cdace5e0ece1df885772763f8f1\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/qimaterials.com\\\/qimc-reports-10-77-hydrogen-mud-gas-reading-at-west-advocate-five-stacked-level-readings-in-a-69-metre-methane-free-hydrogen-rich-interval-in-hole-ddh-26-03-west-advocate-nova-scotia\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/qimaterials.com\\\/qimc-reports-10-77-hydrogen-mud-gas-reading-at-west-advocate-five-stacked-level-readings-in-a-69-metre-methane-free-hydrogen-rich-interval-in-hole-ddh-26-03-west-advocate-nova-scotia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/qimaterials.com\\\/qimc-reports-10-77-hydrogen-mud-gas-reading-at-west-advocate-five-stacked-level-readings-in-a-69-metre-methane-free-hydrogen-rich-interval-in-hole-ddh-26-03-west-advocate-nova-scotia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/qimaterials.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/image.gif\",\"contentUrl\":\"https:\\\/\\\/qimaterials.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/image.gif\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/qimaterials.com\\\/qimc-reports-10-77-hydrogen-mud-gas-reading-at-west-advocate-five-stacked-level-readings-in-a-69-metre-methane-free-hydrogen-rich-interval-in-hole-ddh-26-03-west-advocate-nova-scotia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/qimaterials.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"QIMC Reports 10.77% Hydrogen Mud-Gas Reading at West-Advocate \u2014 Five Stacked %-Level Readings in a 69-Metre Methane-Free Hydrogen-Rich Interval in Hole DDH-26-03, West Advocate, Nova Scotia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/qimaterials.com\\\/#website\",\"url\":\"https:\\\/\\\/qimaterials.com\\\/\",\"name\":\"QIMC\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/qimaterials.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/qimaterials.com\\\/#\\\/schema\\\/person\\\/4b0b8cdace5e0ece1df885772763f8f1\",\"name\":\"OPS OPS\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12558bd0a2074960929cbe42d6b667518297bfc70eeb83e328e69fd5095f8a18?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12558bd0a2074960929cbe42d6b667518297bfc70eeb83e328e69fd5095f8a18?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12558bd0a2074960929cbe42d6b667518297bfc70eeb83e328e69fd5095f8a18?s=96&d=mm&r=g\",\"caption\":\"OPS OPS\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"QIMC signale une concentration de 10,771 TP3T d&#039;hydrog\u00e8ne dans les boues de forage \u00e0 West-Advocate \u2014 Cinq relev\u00e9s superpos\u00e9s de 1 TP3T dans un intervalle de 69 m\u00e8tres riche en hydrog\u00e8ne et exempt de m\u00e9thane, dans le forage DDH-26-03, \u00e0 West Advocate, en Nouvelle-\u00c9cosse - QIMC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/qimaterials.com\/fr\/qimc-reports-10-77-hydrogen-mud-gas-reading-at-west-advocate-five-stacked-level-readings-in-a-69-metre-methane-free-hydrogen-rich-interval-in-hole-ddh-26-03-west-advocate-nova-scotia\/","og_locale":"fr_CA","og_type":"article","og_title":"QIMC Reports 10.77% Hydrogen Mud-Gas Reading at West-Advocate \u2014 Five Stacked %-Level Readings in a 69-Metre Methane-Free Hydrogen-Rich Interval in Hole DDH-26-03, West Advocate, Nova Scotia - QIMC","og_description":"102 IsoJar mud samples return peak 10.77% H\u2082 at 848 m, five readings \u22655% H\u2082 in the 779\u2013848 m interval, three readings \u22657% in a 33-metre sub-interval (815\u2013848 m); methane and CO2 at or below detection Montr\u00e9al, Qu\u00e9bec \u2014 May 20, 2026 \u2014 Qu\u00e9bec Innovative Materials Corp. (CSE: QIMC) (OTCQB: QIMCF) (FSE: 7FJ) (\u201cQIMC\u201d or [&hellip;]","og_url":"https:\/\/qimaterials.com\/fr\/qimc-reports-10-77-hydrogen-mud-gas-reading-at-west-advocate-five-stacked-level-readings-in-a-69-metre-methane-free-hydrogen-rich-interval-in-hole-ddh-26-03-west-advocate-nova-scotia\/","og_site_name":"QIMC","article_published_time":"2026-05-20T11:36:04+00:00","article_modified_time":"2026-05-20T11:36:06+00:00","og_image":[{"width":480,"height":580,"url":"https:\/\/qimaterials.com\/wp-content\/uploads\/2026\/05\/image.gif","type":"image\/gif"}],"author":"OPS OPS","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"OPS OPS","Estimation du temps de lecture":"15 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/qimaterials.com\/qimc-reports-10-77-hydrogen-mud-gas-reading-at-west-advocate-five-stacked-level-readings-in-a-69-metre-methane-free-hydrogen-rich-interval-in-hole-ddh-26-03-west-advocate-nova-scotia\/#article","isPartOf":{"@id":"https:\/\/qimaterials.com\/qimc-reports-10-77-hydrogen-mud-gas-reading-at-west-advocate-five-stacked-level-readings-in-a-69-metre-methane-free-hydrogen-rich-interval-in-hole-ddh-26-03-west-advocate-nova-scotia\/"},"author":{"name":"OPS OPS","@id":"https:\/\/qimaterials.com\/#\/schema\/person\/4b0b8cdace5e0ece1df885772763f8f1"},"headline":"QIMC Reports 10.77% Hydrogen Mud-Gas Reading at West-Advocate \u2014 Five Stacked %-Level Readings in a 69-Metre Methane-Free Hydrogen-Rich Interval in Hole DDH-26-03, West Advocate, Nova Scotia","datePublished":"2026-05-20T11:36:04+00:00","dateModified":"2026-05-20T11:36:06+00:00","mainEntityOfPage":{"@id":"https:\/\/qimaterials.com\/qimc-reports-10-77-hydrogen-mud-gas-reading-at-west-advocate-five-stacked-level-readings-in-a-69-metre-methane-free-hydrogen-rich-interval-in-hole-ddh-26-03-west-advocate-nova-scotia\/"},"wordCount":3108,"image":{"@id":"https:\/\/qimaterials.com\/qimc-reports-10-77-hydrogen-mud-gas-reading-at-west-advocate-five-stacked-level-readings-in-a-69-metre-methane-free-hydrogen-rich-interval-in-hole-ddh-26-03-west-advocate-nova-scotia\/#primaryimage"},"thumbnailUrl":"https:\/\/qimaterials.com\/wp-content\/uploads\/2026\/05\/image.gif","articleSection":["Industry News","Press Releases"],"inLanguage":"fr-CA"},{"@type":"WebPage","@id":"https:\/\/qimaterials.com\/qimc-reports-10-77-hydrogen-mud-gas-reading-at-west-advocate-five-stacked-level-readings-in-a-69-metre-methane-free-hydrogen-rich-interval-in-hole-ddh-26-03-west-advocate-nova-scotia\/","url":"https:\/\/qimaterials.com\/qimc-reports-10-77-hydrogen-mud-gas-reading-at-west-advocate-five-stacked-level-readings-in-a-69-metre-methane-free-hydrogen-rich-interval-in-hole-ddh-26-03-west-advocate-nova-scotia\/","name":"QIMC signale une concentration de 10,771 TP3T d&#039;hydrog\u00e8ne dans les boues de forage \u00e0 West-Advocate \u2014 Cinq relev\u00e9s superpos\u00e9s de 1 TP3T dans un intervalle de 69 m\u00e8tres riche en hydrog\u00e8ne et exempt de m\u00e9thane, dans le forage DDH-26-03, \u00e0 West Advocate, en Nouvelle-\u00c9cosse - QIMC","isPartOf":{"@id":"https:\/\/qimaterials.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/qimaterials.com\/qimc-reports-10-77-hydrogen-mud-gas-reading-at-west-advocate-five-stacked-level-readings-in-a-69-metre-methane-free-hydrogen-rich-interval-in-hole-ddh-26-03-west-advocate-nova-scotia\/#primaryimage"},"image":{"@id":"https:\/\/qimaterials.com\/qimc-reports-10-77-hydrogen-mud-gas-reading-at-west-advocate-five-stacked-level-readings-in-a-69-metre-methane-free-hydrogen-rich-interval-in-hole-ddh-26-03-west-advocate-nova-scotia\/#primaryimage"},"thumbnailUrl":"https:\/\/qimaterials.com\/wp-content\/uploads\/2026\/05\/image.gif","datePublished":"2026-05-20T11:36:04+00:00","dateModified":"2026-05-20T11:36:06+00:00","author":{"@id":"https:\/\/qimaterials.com\/#\/schema\/person\/4b0b8cdace5e0ece1df885772763f8f1"},"breadcrumb":{"@id":"https:\/\/qimaterials.com\/qimc-reports-10-77-hydrogen-mud-gas-reading-at-west-advocate-five-stacked-level-readings-in-a-69-metre-methane-free-hydrogen-rich-interval-in-hole-ddh-26-03-west-advocate-nova-scotia\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/qimaterials.com\/qimc-reports-10-77-hydrogen-mud-gas-reading-at-west-advocate-five-stacked-level-readings-in-a-69-metre-methane-free-hydrogen-rich-interval-in-hole-ddh-26-03-west-advocate-nova-scotia\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/qimaterials.com\/qimc-reports-10-77-hydrogen-mud-gas-reading-at-west-advocate-five-stacked-level-readings-in-a-69-metre-methane-free-hydrogen-rich-interval-in-hole-ddh-26-03-west-advocate-nova-scotia\/#primaryimage","url":"https:\/\/qimaterials.com\/wp-content\/uploads\/2026\/05\/image.gif","contentUrl":"https:\/\/qimaterials.com\/wp-content\/uploads\/2026\/05\/image.gif"},{"@type":"BreadcrumbList","@id":"https:\/\/qimaterials.com\/qimc-reports-10-77-hydrogen-mud-gas-reading-at-west-advocate-five-stacked-level-readings-in-a-69-metre-methane-free-hydrogen-rich-interval-in-hole-ddh-26-03-west-advocate-nova-scotia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/qimaterials.com\/"},{"@type":"ListItem","position":2,"name":"QIMC Reports 10.77% Hydrogen Mud-Gas Reading at West-Advocate \u2014 Five Stacked %-Level Readings in a 69-Metre Methane-Free Hydrogen-Rich Interval in Hole DDH-26-03, West Advocate, Nova Scotia"}]},{"@type":"WebSite","@id":"https:\/\/qimaterials.com\/#website","url":"https:\/\/qimaterials.com\/","name":"QIMC","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/qimaterials.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Person","@id":"https:\/\/qimaterials.com\/#\/schema\/person\/4b0b8cdace5e0ece1df885772763f8f1","name":"OPS OPS","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/12558bd0a2074960929cbe42d6b667518297bfc70eeb83e328e69fd5095f8a18?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/12558bd0a2074960929cbe42d6b667518297bfc70eeb83e328e69fd5095f8a18?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/12558bd0a2074960929cbe42d6b667518297bfc70eeb83e328e69fd5095f8a18?s=96&d=mm&r=g","caption":"OPS OPS"}}]}},"_links":{"self":[{"href":"https:\/\/qimaterials.com\/fr\/wp-json\/wp\/v2\/posts\/83679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/qimaterials.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/qimaterials.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/qimaterials.com\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/qimaterials.com\/fr\/wp-json\/wp\/v2\/comments?post=83679"}],"version-history":[{"count":1,"href":"https:\/\/qimaterials.com\/fr\/wp-json\/wp\/v2\/posts\/83679\/revisions"}],"predecessor-version":[{"id":83682,"href":"https:\/\/qimaterials.com\/fr\/wp-json\/wp\/v2\/posts\/83679\/revisions\/83682"}],"wp:attachment":[{"href":"https:\/\/qimaterials.com\/fr\/wp-json\/wp\/v2\/media?parent=83679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/qimaterials.com\/fr\/wp-json\/wp\/v2\/categories?post=83679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/qimaterials.com\/fr\/wp-json\/wp\/v2\/tags?post=83679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}