{"id":20052,"date":"2024-12-05T13:25:34","date_gmt":"2024-12-05T13:25:34","guid":{"rendered":"https:\/\/qimaterials.com\/?st-import=4438370e7b782d0f5ce5e71f6ed04def"},"modified":"2026-05-14T15:27:43","modified_gmt":"2026-05-14T15:27:43","slug":"qimc-announces-landmark-gravimetric-results-for-the-ville-marie-clean-natural-renewable-hydrogen-project","status":"publish","type":"post","link":"https:\/\/qimaterials.com\/fr\/qimc-announces-landmark-gravimetric-results-for-the-ville-marie-clean-natural-renewable-hydrogen-project\/","title":{"rendered":"QIMC annonce des r\u00e9sultats gravim\u00e9triques marquants pour le projet d&#039;hydrog\u00e8ne propre, naturel et renouvelable de Ville Marie"},"content":{"rendered":"<p>Lachute (Qu\u00e9bec), le 5 d\u00e9cembre 2024 \u2013 Quebec Innovative Materials Corp. (CSE\u00a0: QIMC, FSE\u00a0: 7FJ OTC Pink\u00a0: QIMCF) (\u201c\u00a0QI Materials\u00a0\u201d, \u201c\u00a0QIMC\u00a0\u201d ou la \u201c\u00a0Soci\u00e9t\u00e9\u00a0\u201d), \u2013 QIMC est heureuse d\u2019annoncer de nouveaux r\u00e9sultats marquants de la r\u00e9cente \u00e9tude gravim\u00e9trique r\u00e9gionale men\u00e9e dans le cadre de sa campagne d\u2019exploration automnale 2024 pour le projet d\u2019hydrog\u00e8ne renouvelable naturel propre de Ville Marie. \u201c\u00a0Ces nouvelles donn\u00e9es joueront un r\u00f4le essentiel dans l\u2019avancement du d\u00e9veloppement et de l\u2019extraction d\u2019hydrog\u00e8ne dans la r\u00e9gion, et r\u00e9affirmeront notre engagement envers l\u2019\u00e9nergie propre et le d\u00e9veloppement durable de l\u2019hydrog\u00e8ne\u00a0\u201d, souligne John Karagiannidis, chef de la direction de QIMC.<\/p>\n<p>Le lev\u00e9 gravim\u00e9trique, r\u00e9alis\u00e9 par l&#039;INRS avec un espacement de 50 m\u00e8tres le long des lignes \u00e9tablies lors du lev\u00e9 sol-gaz de l&#039;\u00e9t\u00e9 2024, fournit des informations essentielles sur la g\u00e9ologie arch\u00e9enne profonde sous les couvertures de roches s\u00e9dimentaires prot\u00e9rozo\u00efques (voir figure 1). Celles-ci comprennent le Groupe Cobalt et les roches ordoviciennes du Groupe New-Liskeard. \u201c L&#039;objectif principal de ce lev\u00e9 \u00e9tait d&#039;am\u00e9liorer notre compr\u00e9hension des formations g\u00e9ologiques qui contribuent \u00e0 la formation et \u00e0 la migration de l&#039;hydrog\u00e8ne, notamment dans le cadre du mod\u00e8le d&#039;exploration du graben de T\u00e9miscamingue \u201d, explique le professeur Marc Richer-Lafleche.<\/p>\n<p><img class=\"\\\"alignnone\" size-full wp-image-20054\\\" src=\"\\\"https:><\/p>\n<p>&nbsp;<\/p>\n<p>Figure 1 \u2013 Carte de variabilit\u00e9 des valeurs d\u2019anomalie de Bouguer pour la r\u00e9gion de Saint-Bruno-de-Guigues (T\u00e9miscamingue, QC). Les donn\u00e9es sur l\u2019hydrog\u00e8ne mesur\u00e9es dans les sols sont superpos\u00e9es.<\/p>\n<p>Principaux enseignements tir\u00e9s des r\u00e9sultats gravim\u00e9triques\u00a0:<\/p>\n<ul>\n<li><strong>Les roches arch\u00e9ennes comme sources potentielles d&#039;hydrog\u00e8ne<\/strong>Les r\u00e9sultats de l&#039;\u00e9tude mettent en \u00e9vidence la pr\u00e9sence de formations g\u00e9ologiques arch\u00e9ennes cl\u00e9s, telles que des p\u00e9ridotites, des komatiites, des basaltes et des formations de fer, qui constituent des sources essentielles d&#039;hydrog\u00e8ne. Ces formations jouent un r\u00f4le central dans nos efforts de production d&#039;hydrog\u00e8ne, pla\u00e7ant ainsi QIMC \u00e0 l&#039;avant-garde de l&#039;extraction d&#039;\u00e9nergie propre.<\/li>\n<li><strong>Carte des anomalies de Bouguer<\/strong>Les donn\u00e9es de l&#039;\u00e9tude ont \u00e9t\u00e9 visualis\u00e9es sous la forme d&#039;une carte d&#039;anomalie de Bouguer classique, offrant une vision objective et d\u00e9taill\u00e9e des variations de gravit\u00e9 dans la r\u00e9gion. La carte r\u00e9v\u00e8le clairement la forte anisotropie des donn\u00e9es gravim\u00e9triques, refl\u00e9tant les contrastes de densit\u00e9 entre diff\u00e9rentes formations g\u00e9ologiques arch\u00e9ennes. Les caract\u00e9ristiques g\u00e9ologiques de ces formations sont essentielles \u00e0 la compr\u00e9hension du potentiel en hydrog\u00e8ne de la zone.<\/li>\n<li><strong>D\u00e9couvertes cl\u00e9s<\/strong>:\n<ul>\n<li><strong>Domaine A<\/strong>Les faibles valeurs de gravit\u00e9 dans cette r\u00e9gion du sud-est indiquent la pr\u00e9sence du pluton granitique du Lac des Seize.<\/li>\n<li><strong>Domaines B, C et E<\/strong>Ces domaines sont enrichis en roches volcaniques et intrusives de la ceinture volcanique du groupe Baby, qui pr\u00e9sentent une importance g\u00e9ologique significative pour le stockage et la migration de l&#039;hydrog\u00e8ne.<\/li>\n<li><strong>Domaine D<\/strong>Les structures lin\u00e9aires de ce domaine correspondent \u00e0 une zone de faille arch\u00e9enne r\u00e9cemment identifi\u00e9e, qui joue un r\u00f4le crucial dans la mise en place des concentrations d&#039;hydrog\u00e8ne observ\u00e9es dans la r\u00e9gion. Cette zone de faille nouvellement d\u00e9couverte constitue un axe de recherche prioritaire, car elle pourrait contribuer directement \u00e0 la formation et \u00e0 la migration de l&#039;hydrog\u00e8ne.<\/li>\n<li><strong>Domaine F<\/strong>Des valeurs de gravit\u00e9 \u00e9lev\u00e9es et inattendues dans cette zone ont permis la d\u00e9couverte d&#039;un affleurement de dyke de Nipissing recoupant les roches s\u00e9dimentaires du Groupe Cobalt. Ce dyke, ou filon-couche, devrait s&#039;agrandir avec la profondeur et pourrait constituer une barri\u00e8re imperm\u00e9able essentielle \u00e0 l&#039;accumulation et \u00e0 la r\u00e9tention d&#039;hydrog\u00e8ne, \u00e0 l&#039;instar des m\u00e9canismes observ\u00e9s dans d&#039;autres gisements d&#039;hydrog\u00e8ne \u00e0 travers le monde.<\/li>\n<li><strong>Domaine G<\/strong>Nous avons identifi\u00e9 des zones d&#039;accumulation de calcaire et de dolomie, reposant en discordance sur des roches s\u00e9dimentaires prot\u00e9rozo\u00efques. Ces zones pourraient apporter un \u00e9clairage nouveau sur les conditions g\u00e9ologiques propices au stockage de l&#039;hydrog\u00e8ne.<\/li>\n<\/ul>\n<\/li>\n<li><strong>Zones d&#039;hydrog\u00e8ne \u00e0 haute valeur ajout\u00e9e<\/strong>L&#039;une des d\u00e9couvertes les plus int\u00e9ressantes a \u00e9t\u00e9 la mise en \u00e9vidence de valeurs gravim\u00e9triques \u00e9lev\u00e9es \u00e0 la jonction du profil de gaz du sol de la ligne 7 (longueur de 10 km) et de la zone de faille arch\u00e9enne pr\u00e9sum\u00e9e (domaine D). \u201c Cette zone semble abriter une r\u00e9gion tr\u00e8s perm\u00e9able, form\u00e9e par l&#039;intersection d&#039;une structure cassante nord-sud associ\u00e9e au graben de T\u00e9miscamingue et de la faille arch\u00e9enne \u201c, explique le professeur Richer-Lafleche. \u201c Cette structure nouvellement identifi\u00e9e pourrait receler de fortes concentrations d&#039;hydrog\u00e8ne. \u201d<\/li>\n<\/ul>\n<p>\u201c Ces r\u00e9sultats gravim\u00e9triques exceptionnels offrent un aper\u00e7u convaincant du potentiel hydrog\u00e8ne de la r\u00e9gion et ouvrent la voie \u00e0 la prochaine phase de notre programme, en parall\u00e8le de nos activit\u00e9s de surveillance et de mesure \u201d, commente John Karagiannidis. Ces donn\u00e9es g\u00e9ologiques contribueront de fa\u00e7on significative au succ\u00e8s du projet d\u2019hydrog\u00e8ne propre, naturel et renouvelable de Ville-Marie, et r\u00e9affirment notre engagement \u00e0 promouvoir les solutions \u00e9nerg\u00e9tiques renouvelables et le programme d\u2019\u00e9nergie propre du Qu\u00e9bec.<\/p>\n<p>Nous avons h\u00e2te de tenir les parties prenantes, les partenaires et le public inform\u00e9s de l&#039;avancement de nos travaux dans ce domaine passionnant et en pleine transformation.<\/p>\n<p><strong>\u00c0 propos de l\u2019INRS et du Pr Marc Richer-LaFl\u00e8che, P.Geo.<\/strong><\/p>\n<p>L\u2019Institut national de la recherche scientifique (INRS) est un institut de recherche et de formation de haut niveau. L\u2019\u00e9quipe du Pr Richer-LaFl\u00e8che poss\u00e8de une expertise exceptionnelle en g\u00e9ologie, g\u00e9ochimie et g\u00e9ophysique, notamment dans les r\u00e9gions des concessions r\u00e9cemment acquises par QIMC. Elle a men\u00e9 plus de six ann\u00e9es de travaux g\u00e9ophysiques et g\u00e9ochimiques et r\u00e9alis\u00e9 des milliers d\u2019analyses de gaz du sol (C1-C4).<\/p>\n<ol>\n<li>Richer-LaFl\u00e8che d\u00e9tient \u00e9galement une subvention du FRQNT, en partenariat avec le R\u00e9seau des mines et de la g\u00e9ologie du Qu\u00e9bec et l\u2019industrie mini\u00e8re, pour d\u00e9velopper et optimiser une m\u00e9thode d\u2019analyse des gaz du sol permettant la d\u00e9tection directe des corps min\u00e9ralis\u00e9s et des failles sous la couverture quaternaire. Outre les gaz sulfur\u00e9s, l\u2019hydrog\u00e8ne a \u00e9t\u00e9 syst\u00e9matiquement analys\u00e9 lors des nombreuses campagnes de lev\u00e9s effectu\u00e9es en 2023 en Abitibi, \u00e0 T\u00e9miscamingue et dans les Appachies qu\u00e9b\u00e9coises. M. Richer-LaFl\u00e8che est la personne qualifi\u00e9e responsable de l\u2019information technique contenue dans ce communiqu\u00e9 et en a pris connaissance.<\/li>\n<\/ol>\n<p>De plus, l\u2019\u00e9quipe de l\u2019INRS dispose de plusieurs spectrom\u00e8tres \u00e0 gaz portables ainsi que du mat\u00e9riel d\u2019\u00e9chantillonnage et de la logistique n\u00e9cessaires pour pr\u00e9lever des \u00e9chantillons de gaz et effectuer des mesures g\u00e9ophysiques sur le terrain ou en milieu aquatique. Il est g\u00e9ologue professionnel, membre de l\u2019Ordre des g\u00e9ologues du Qu\u00e9bec et est la personne qualifi\u00e9e responsable de l\u2019information technique contenue dans ce communiqu\u00e9. Il a pris connaissance de l\u2019information qui y est pr\u00e9sent\u00e9e.<\/p>\n<p>Pour plus d&#039;informations sur la Soci\u00e9t\u00e9 des mat\u00e9riaux innovants du Qu\u00e9bec et ses produits, veuillez consulter le site Web suivant\u00a0: <a href=\"\/fr\/\"http:>www.qimaterials.com<\/a><\/p>\n<p><strong>\u00c0 propos de la Soci\u00e9t\u00e9 des mat\u00e9riaux innovants du Qu\u00e9bec.<\/strong><\/p>\n<p>Qu\u00e9bec Innovative Materials Corp. est une soci\u00e9t\u00e9 d&#039;exploration et de d\u00e9veloppement minier qui se consacre \u00e0 l&#039;exploration et \u00e0 l&#039;exploitation du potentiel des abondantes ressources du Canada. Poss\u00e9dant des propri\u00e9t\u00e9s en Ontario et au Qu\u00e9bec, QIMC se sp\u00e9cialise dans l&#039;exploration de gisements d&#039;hydrog\u00e8ne blanc (naturel) et de silice \u00e0 haute teneur. QIMC s&#039;engage \u00e0 adopter des pratiques durables et \u00e0 innover. Ax\u00e9e sur la g\u00e9rance environnementale et l&#039;utilisation de technologies d&#039;extraction de pointe, notre entreprise vise \u00e0 lib\u00e9rer tout le potentiel de ces mat\u00e9riaux afin de favoriser des solutions \u00e9nerg\u00e9tiques propres pour alimenter l&#039;intelligence artificielle et une \u00e9conomie carboneutre et contribuer \u00e0 un avenir plus durable.<\/p>\n<p><strong>QU\u00c9BEC MAT\u00c9RIAUX INNOVANTS CORP.<\/strong><\/p>\n<p>John Karagiannidis<\/p>\n<p>Directeur g\u00e9n\u00e9ral<\/p>\n<p>T\u00e9l. : +1 438-401-8271<\/p>\n<p>Pour plus d&#039;informations, veuillez contacter\u00a0:<\/p>\n<p>E-mail: <a href=\"\/fr\/\"mailto:info@qimaterials.com\\\"\">info@qimaterials.com <\/a><\/p>\n<p><strong><em>Ni la Bourse canadienne des valeurs mobili\u00e8res ni son fournisseur de services de r\u00e9glementation (tel que ce terme est d\u00e9fini dans les politiques de la CSE) n&#039;acceptent la responsabilit\u00e9 de l&#039;exactitude ou de l&#039;exhaustivit\u00e9 du pr\u00e9sent communiqu\u00e9 et n&#039;ont ni approuv\u00e9 ni d\u00e9sapprouv\u00e9 son contenu.<\/em>se.<\/strong><\/p>\n<p><strong>D\u00e9clarations prospectives<\/strong><\/p>\n<p><em>Ce communiqu\u00e9 contient des \u00e9nonc\u00e9s prospectifs. Ces \u00e9nonc\u00e9s prospectifs comportent des risques connus et inconnus, des incertitudes et d\u2019autres facteurs qui pourraient faire en sorte que les r\u00e9sultats, le rendement ou les r\u00e9alisations r\u00e9els de Qu\u00e9bec Mat\u00e9riaux Innovants, ou l\u2019\u00e9volution du secteur, diff\u00e8rent sensiblement des r\u00e9sultats, du rendement ou des r\u00e9alisations anticip\u00e9s, exprim\u00e9s ou sous-entendus par ces \u00e9nonc\u00e9s prospectifs. Les \u00e9nonc\u00e9s prospectifs ne constituent pas des faits historiques et sont g\u00e9n\u00e9ralement, mais pas toujours, identifi\u00e9s par des termes comme \u201d pr\u00e9voit \u201d, \u2019 planifie \u201d, \u201d anticipe \u201d, \u201d croit \u201d, \u201d a l\u2019intention de \u201d, \u201d estime \u201d, \u201d projette \u201d, \u201d potentiel \u201d et autres expressions similaires, ou par l\u2019emploi des verbes \u201d se r\u00e9aliser \u201d, \u201d pourrait se r\u00e9aliser \u201d, \u201d pourrait se r\u00e9aliser \u201d ou \u201d devrait se r\u00e9aliser \u201d.<\/em><\/p>\n<p><em>Bien que Qu\u00e9bec Mat\u00e9riaux Innovants estime que les informations prospectives contenues dans ce communiqu\u00e9 de presse soient raisonnables compte tenu des informations disponibles \u00e0 la date des pr\u00e9sentes, de par leur nature, les \u00e9nonc\u00e9s prospectifs comportent des hypoth\u00e8ses, des risques connus et inconnus, des incertitudes et d\u2019autres facteurs qui pourraient faire en sorte que nos r\u00e9sultats, notre rendement ou nos r\u00e9alisations r\u00e9els, ou d\u2019autres \u00e9v\u00e9nements futurs, diff\u00e8rent sensiblement des r\u00e9sultats, du rendement ou des r\u00e9alisations futurs exprim\u00e9s ou sous-entendus par ces \u00e9nonc\u00e9s prospectifs.<\/em><\/p>\n<p><em>Ces hypoth\u00e8ses, risques et incertitudes comprennent, sans toutefois s&#039;y limiter, ceux li\u00e9s \u00e0 la conjoncture \u00e9conomique g\u00e9n\u00e9rale; aux \u00e9v\u00e9nements d\u00e9favorables touchant l&#039;industrie; \u00e0 l&#039;\u00e9volution future de la l\u00e9gislation et de la r\u00e9glementation dans le secteur minier; \u00e0 la capacit\u00e9 de la Soci\u00e9t\u00e9 d&#039;obtenir des capitaux suffisants de sources internes et externes, ou \u00e0 son incapacit\u00e9 d&#039;obtenir des capitaux suffisants \u00e0 des conditions favorables; \u00e0 l&#039;industrie et aux march\u00e9s miniers au Canada et en g\u00e9n\u00e9ral; \u00e0 la capacit\u00e9 de Qu\u00e9bec Mat\u00e9riaux Innovants Corp. de mettre en \u0153uvre ses strat\u00e9gies commerciales; \u00e0 la concurrence; et \u00e0 d&#039;autres hypoth\u00e8ses, risques et incertitudes.<\/em><\/p>\n<p><em>Les informations prospectives contenues dans ce communiqu\u00e9 de presse refl\u00e8tent les attentes de la Soci\u00e9t\u00e9 \u00e0 la date de publication et sont donc susceptibles d&#039;\u00e9voluer. Les lecteurs ne doivent pas accorder une importance excessive \u00e0 ces informations prospectives et ne doivent pas s&#039;y fier \u00e0 une date ult\u00e9rieure. Bien que la Soci\u00e9t\u00e9 puisse choisir de le faire, elle ne s&#039;engage pas \u00e0 mettre \u00e0 jour ces informations \u00e0 un moment pr\u00e9cis, sauf si la loi l&#039;exige.<\/em><\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Lachute, Quebec, December 5, 2024\u2013- Quebec Innovative Materials Corp. (CSE: QIMC, FSE: 7FJ OTC Pink: QIMCF)\u00a0 (\u201cQI Materials\u201d, \u201cQIMC\u201d or the \u201cCompany\u201d), \u2013 QIMC is pleased to announce another set of landmark results from the recent regional gravity survey conducted as part of our ongoing Fall 2024 exploration campaign for the Ville Marie Clean Natural [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":978,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","iawp_total_views":3,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-20052","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press-releases"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>QIMC Announces Landmark Gravimetric Results for the Ville Marie Clean Natural Renewable Hydrogen Project - QIMC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/qimaterials.com\/fr\/qimc-announces-landmark-gravimetric-results-for-the-ville-marie-clean-natural-renewable-hydrogen-project\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"QIMC Announces Landmark Gravimetric Results for the Ville Marie Clean Natural Renewable Hydrogen Project - QIMC\" \/>\n<meta property=\"og:description\" content=\"Lachute, Quebec, December 5, 2024\u2013- Quebec Innovative Materials Corp. (CSE: QIMC, FSE: 7FJ OTC Pink: QIMCF)\u00a0 (\u201cQI Materials\u201d, \u201cQIMC\u201d or the \u201cCompany\u201d), \u2013 QIMC is pleased to announce another set of landmark results from the recent regional gravity survey conducted as part of our ongoing Fall 2024 exploration campaign for the Ville Marie Clean Natural [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/qimaterials.com\/fr\/qimc-announces-landmark-gravimetric-results-for-the-ville-marie-clean-natural-renewable-hydrogen-project\/\" \/>\n<meta property=\"og:site_name\" content=\"QIMC\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-05T13:25:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-14T15:27:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/qimaterials.com\/wp-content\/uploads\/2024\/07\/newpos2-min.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"QIMC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"QIMC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/qimaterials.com\\\/qimc-announces-landmark-gravimetric-results-for-the-ville-marie-clean-natural-renewable-hydrogen-project\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/qimaterials.com\\\/qimc-announces-landmark-gravimetric-results-for-the-ville-marie-clean-natural-renewable-hydrogen-project\\\/\"},\"author\":{\"name\":\"QIMC\",\"@id\":\"https:\\\/\\\/qimaterials.com\\\/#\\\/schema\\\/person\\\/39435340349b65729b1463189bf3d52e\"},\"headline\":\"QIMC Announces Landmark Gravimetric Results for the Ville Marie Clean Natural Renewable Hydrogen Project\",\"datePublished\":\"2024-12-05T13:25:34+00:00\",\"dateModified\":\"2026-05-14T15:27:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/qimaterials.com\\\/qimc-announces-landmark-gravimetric-results-for-the-ville-marie-clean-natural-renewable-hydrogen-project\\\/\"},\"wordCount\":1426,\"image\":{\"@id\":\"https:\\\/\\\/qimaterials.com\\\/qimc-announces-landmark-gravimetric-results-for-the-ville-marie-clean-natural-renewable-hydrogen-project\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/qimaterials.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/newpos2-min.jpg\",\"articleSection\":[\"Press Releases\"],\"inLanguage\":\"fr-CA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/qimaterials.com\\\/qimc-announces-landmark-gravimetric-results-for-the-ville-marie-clean-natural-renewable-hydrogen-project\\\/\",\"url\":\"https:\\\/\\\/qimaterials.com\\\/qimc-announces-landmark-gravimetric-results-for-the-ville-marie-clean-natural-renewable-hydrogen-project\\\/\",\"name\":\"QIMC Announces Landmark Gravimetric Results for the Ville Marie Clean Natural Renewable Hydrogen Project - QIMC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/qimaterials.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/qimaterials.com\\\/qimc-announces-landmark-gravimetric-results-for-the-ville-marie-clean-natural-renewable-hydrogen-project\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/qimaterials.com\\\/qimc-announces-landmark-gravimetric-results-for-the-ville-marie-clean-natural-renewable-hydrogen-project\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/qimaterials.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/newpos2-min.jpg\",\"datePublished\":\"2024-12-05T13:25:34+00:00\",\"dateModified\":\"2026-05-14T15:27:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/qimaterials.com\\\/#\\\/schema\\\/person\\\/39435340349b65729b1463189bf3d52e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/qimaterials.com\\\/qimc-announces-landmark-gravimetric-results-for-the-ville-marie-clean-natural-renewable-hydrogen-project\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/qimaterials.com\\\/qimc-announces-landmark-gravimetric-results-for-the-ville-marie-clean-natural-renewable-hydrogen-project\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/qimaterials.com\\\/qimc-announces-landmark-gravimetric-results-for-the-ville-marie-clean-natural-renewable-hydrogen-project\\\/#primaryimage\",\"url\":\"https:\\\/\\\/qimaterials.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/newpos2-min.jpg\",\"contentUrl\":\"https:\\\/\\\/qimaterials.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/newpos2-min.jpg\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/qimaterials.com\\\/qimc-announces-landmark-gravimetric-results-for-the-ville-marie-clean-natural-renewable-hydrogen-project\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/qimaterials.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"QIMC Announces Landmark Gravimetric Results for the Ville Marie Clean Natural Renewable Hydrogen Project\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/qimaterials.com\\\/#website\",\"url\":\"https:\\\/\\\/qimaterials.com\\\/\",\"name\":\"QIMC\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/qimaterials.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/qimaterials.com\\\/#\\\/schema\\\/person\\\/39435340349b65729b1463189bf3d52e\",\"name\":\"QIMC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/be8e855ddb2feed9f69b34fe07d3bbe8170061f3d521894bb1b409ca52c7d750?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/be8e855ddb2feed9f69b34fe07d3bbe8170061f3d521894bb1b409ca52c7d750?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/be8e855ddb2feed9f69b34fe07d3bbe8170061f3d521894bb1b409ca52c7d750?s=96&d=mm&r=g\",\"caption\":\"QIMC\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"QIMC annonce des r\u00e9sultats gravim\u00e9triques historiques pour le projet d&#039;hydrog\u00e8ne propre, naturel et renouvelable de Ville Marie - QIMC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/qimaterials.com\/fr\/qimc-announces-landmark-gravimetric-results-for-the-ville-marie-clean-natural-renewable-hydrogen-project\/","og_locale":"fr_CA","og_type":"article","og_title":"QIMC Announces Landmark Gravimetric Results for the Ville Marie Clean Natural Renewable Hydrogen Project - QIMC","og_description":"Lachute, Quebec, December 5, 2024\u2013- Quebec Innovative Materials Corp. (CSE: QIMC, FSE: 7FJ OTC Pink: QIMCF)\u00a0 (\u201cQI Materials\u201d, \u201cQIMC\u201d or the \u201cCompany\u201d), \u2013 QIMC is pleased to announce another set of landmark results from the recent regional gravity survey conducted as part of our ongoing Fall 2024 exploration campaign for the Ville Marie Clean Natural [&hellip;]","og_url":"https:\/\/qimaterials.com\/fr\/qimc-announces-landmark-gravimetric-results-for-the-ville-marie-clean-natural-renewable-hydrogen-project\/","og_site_name":"QIMC","article_published_time":"2024-12-05T13:25:34+00:00","article_modified_time":"2026-05-14T15:27:43+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/qimaterials.com\/wp-content\/uploads\/2024\/07\/newpos2-min.jpg","type":"image\/jpeg"}],"author":"QIMC","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"QIMC","Estimation du temps de lecture":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/qimaterials.com\/qimc-announces-landmark-gravimetric-results-for-the-ville-marie-clean-natural-renewable-hydrogen-project\/#article","isPartOf":{"@id":"https:\/\/qimaterials.com\/qimc-announces-landmark-gravimetric-results-for-the-ville-marie-clean-natural-renewable-hydrogen-project\/"},"author":{"name":"QIMC","@id":"https:\/\/qimaterials.com\/#\/schema\/person\/39435340349b65729b1463189bf3d52e"},"headline":"QIMC Announces Landmark Gravimetric Results for the Ville Marie Clean Natural Renewable Hydrogen Project","datePublished":"2024-12-05T13:25:34+00:00","dateModified":"2026-05-14T15:27:43+00:00","mainEntityOfPage":{"@id":"https:\/\/qimaterials.com\/qimc-announces-landmark-gravimetric-results-for-the-ville-marie-clean-natural-renewable-hydrogen-project\/"},"wordCount":1426,"image":{"@id":"https:\/\/qimaterials.com\/qimc-announces-landmark-gravimetric-results-for-the-ville-marie-clean-natural-renewable-hydrogen-project\/#primaryimage"},"thumbnailUrl":"https:\/\/qimaterials.com\/wp-content\/uploads\/2024\/07\/newpos2-min.jpg","articleSection":["Press Releases"],"inLanguage":"fr-CA"},{"@type":"WebPage","@id":"https:\/\/qimaterials.com\/qimc-announces-landmark-gravimetric-results-for-the-ville-marie-clean-natural-renewable-hydrogen-project\/","url":"https:\/\/qimaterials.com\/qimc-announces-landmark-gravimetric-results-for-the-ville-marie-clean-natural-renewable-hydrogen-project\/","name":"QIMC annonce des r\u00e9sultats gravim\u00e9triques historiques pour le projet d&#039;hydrog\u00e8ne propre, naturel et renouvelable de Ville Marie - QIMC","isPartOf":{"@id":"https:\/\/qimaterials.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/qimaterials.com\/qimc-announces-landmark-gravimetric-results-for-the-ville-marie-clean-natural-renewable-hydrogen-project\/#primaryimage"},"image":{"@id":"https:\/\/qimaterials.com\/qimc-announces-landmark-gravimetric-results-for-the-ville-marie-clean-natural-renewable-hydrogen-project\/#primaryimage"},"thumbnailUrl":"https:\/\/qimaterials.com\/wp-content\/uploads\/2024\/07\/newpos2-min.jpg","datePublished":"2024-12-05T13:25:34+00:00","dateModified":"2026-05-14T15:27:43+00:00","author":{"@id":"https:\/\/qimaterials.com\/#\/schema\/person\/39435340349b65729b1463189bf3d52e"},"breadcrumb":{"@id":"https:\/\/qimaterials.com\/qimc-announces-landmark-gravimetric-results-for-the-ville-marie-clean-natural-renewable-hydrogen-project\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/qimaterials.com\/qimc-announces-landmark-gravimetric-results-for-the-ville-marie-clean-natural-renewable-hydrogen-project\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/qimaterials.com\/qimc-announces-landmark-gravimetric-results-for-the-ville-marie-clean-natural-renewable-hydrogen-project\/#primaryimage","url":"https:\/\/qimaterials.com\/wp-content\/uploads\/2024\/07\/newpos2-min.jpg","contentUrl":"https:\/\/qimaterials.com\/wp-content\/uploads\/2024\/07\/newpos2-min.jpg","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/qimaterials.com\/qimc-announces-landmark-gravimetric-results-for-the-ville-marie-clean-natural-renewable-hydrogen-project\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/qimaterials.com\/"},{"@type":"ListItem","position":2,"name":"QIMC Announces Landmark Gravimetric Results for the Ville Marie Clean Natural Renewable Hydrogen Project"}]},{"@type":"WebSite","@id":"https:\/\/qimaterials.com\/#website","url":"https:\/\/qimaterials.com\/","name":"QIMC","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/qimaterials.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Person","@id":"https:\/\/qimaterials.com\/#\/schema\/person\/39435340349b65729b1463189bf3d52e","name":"QIMC","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/be8e855ddb2feed9f69b34fe07d3bbe8170061f3d521894bb1b409ca52c7d750?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/be8e855ddb2feed9f69b34fe07d3bbe8170061f3d521894bb1b409ca52c7d750?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/be8e855ddb2feed9f69b34fe07d3bbe8170061f3d521894bb1b409ca52c7d750?s=96&d=mm&r=g","caption":"QIMC"}}]}},"_links":{"self":[{"href":"https:\/\/qimaterials.com\/fr\/wp-json\/wp\/v2\/posts\/20052","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/qimaterials.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/qimaterials.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/qimaterials.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/qimaterials.com\/fr\/wp-json\/wp\/v2\/comments?post=20052"}],"version-history":[{"count":1,"href":"https:\/\/qimaterials.com\/fr\/wp-json\/wp\/v2\/posts\/20052\/revisions"}],"predecessor-version":[{"id":83566,"href":"https:\/\/qimaterials.com\/fr\/wp-json\/wp\/v2\/posts\/20052\/revisions\/83566"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/qimaterials.com\/fr\/wp-json\/wp\/v2\/media\/978"}],"wp:attachment":[{"href":"https:\/\/qimaterials.com\/fr\/wp-json\/wp\/v2\/media?parent=20052"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/qimaterials.com\/fr\/wp-json\/wp\/v2\/categories?post=20052"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/qimaterials.com\/fr\/wp-json\/wp\/v2\/tags?post=20052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}