{"id":1213,"date":"2024-09-11T12:36:59","date_gmt":"2024-09-11T12:36:59","guid":{"rendered":"https:\/\/qimaterials.com\/?st-import=b2b7a6cffdec02b0e432cfe1d1dc6340"},"modified":"2026-05-14T15:27:43","modified_gmt":"2026-05-14T15:27:43","slug":"qimc-announces-successful-exercise-of-warrants-and-strategic-advances-in-fully-funded-hydrogen-exploration-program","status":"publish","type":"post","link":"https:\/\/qimaterials.com\/fr\/qimc-announces-successful-exercise-of-warrants-and-strategic-advances-in-fully-funded-hydrogen-exploration-program\/","title":{"rendered":"QIMC annonce l&#039;exercice r\u00e9ussi de ses bons de souscription et des avanc\u00e9es strat\u00e9giques dans son programme d&#039;exploration d&#039;hydrog\u00e8ne enti\u00e8rement financ\u00e9."},"content":{"rendered":"<p>Lachute (Qu\u00e9bec), le 11 septembre 2024 \u2013 Quebec Innovative Materials Corp. (CSE\u00a0: QIMC, FSE\u00a0: 7FJ) (\u201c\u00a0QI Materials\u00a0\u201d, \u201c\u00a0QIMC\u00a0\u201d ou la \u201c\u00a0Soci\u00e9t\u00e9\u00a0\u201d) \u2013 QIMC est heureuse d\u2019annoncer l\u2019exercice r\u00e9ussi de 9,915 millions de bons de souscription, ce qui repr\u00e9sente une autre avanc\u00e9e significative dans ses initiatives li\u00e9es \u00e0 l\u2019hydrog\u00e8ne. \u201c\u00a0Cette r\u00e9alisation t\u00e9moigne de la grande confiance de nos actionnaires envers notre mission et notre strat\u00e9gie\u00a0\u2019, a d\u00e9clar\u00e9 John Karagiannidis, pr\u00e9sident de QIMC. \u201d\u00a0Nous remercions nos actionnaires de leur soutien et de leur engagement constants, qui nous ont permis de devenir un chef de file nord-am\u00e9ricain, bien situ\u00e9, dans l\u2019exploration de l\u2019hydrog\u00e8ne naturel. Nous sommes \u00e9galement fiers de figurer \u00e0 l\u2019indice NHV Nat H2, le premier indice de l\u2019hydrog\u00e8ne naturel.\u00a0\u201c<\/p>\n<p>Les recettes des exercices de warrants viendront s&#039;ajouter \u00e0 la prochaine phase de notre programme d&#039;exploration d&#039;hydrog\u00e8ne naturel de Ville Marie, enti\u00e8rement financ\u00e9 par l&#039;Institut National de la Recherche Scientifique (INRS), pour lequel nous sommes \u00e9galement ravis d&#039;annoncer que notre partenaire strat\u00e9gique, l&#039;INRS, commencera la semaine prochaine une s\u00e9rie de lev\u00e9s g\u00e9ophysiques avanc\u00e9s de gravim\u00e9trie et d&#039;audiomagnetotellurisme (AMT).<\/p>\n<p>Les lev\u00e9s gravim\u00e9triques viseront \u00e0 \u00e9valuer les variations d&#039;\u00e9paisseur des d\u00e9p\u00f4ts s\u00e9dimentaires locaux, appel\u00e9s bassins gravim\u00e9triques, sur le socle arch\u00e9en. Ces donn\u00e9es essentielles nous aideront \u00e0 identifier les zones les plus susceptibles de contenir des roches r\u00e9servoirs pr\u00e9cieuses. Parall\u00e8lement, les lev\u00e9s AMT seront d\u00e9terminants pour localiser les failles associ\u00e9es aux grabens dans la r\u00e9gion de Saint-Bruno-de-Guigues.<\/p>\n<p>Nous sommes \u00e9galement ravis d&#039;annoncer le lancement de notre programme d&#039;exploration d&#039;hydrog\u00e8ne de l&#039;INRS au lac Saint-Jean, qui d\u00e9butera en novembre. <u>Il s&#039;agit d&#039;une avanc\u00e9e significative dans notre strat\u00e9gie visant \u00e0 d\u00e9velopper nos capacit\u00e9s d&#039;exploration et de production d&#039;hydrog\u00e8ne, soutenant ainsi notre objectif de devenir un chef de file de l&#039;\u00e9conomie de l&#039;hydrog\u00e8ne.<\/u><\/p>\n<p><strong><em><u>Lac Saint-Jean<\/u><\/em><\/strong><\/p>\n<p><u>\u201c Outre la prise en compte des caract\u00e9ristiques g\u00e9ologiques essentielles \u00e0 l\u2019identification des zones d\u2019exploration, QIMC privil\u00e9gie les secteurs \u00e9conomiquement favorables \u00e0 l\u2019implantation d\u2019usines \u00e0 hydrog\u00e8ne \u201d, a d\u00e9clar\u00e9 John Karagiannid.<\/u>\u201c\u00a0Par exemple, l\u2019int\u00e9r\u00eat strat\u00e9gique de la r\u00e9gion du Saguenay\u2013Lac-Saint-Jean repose sur la pr\u00e9sence d\u2019une infrastructure portuaire en eau profonde \u00e0 La Baie (Alma) (figure\u00a01). Cela permettrait d\u2019exporter de l\u2019hydrog\u00e8ne (solide ou gazeux) vers les march\u00e9s europ\u00e9ens, asiatiques ou am\u00e9ricains bordant l\u2019oc\u00e9an Atlantique\u00a0\u201d, a d\u00e9clar\u00e9 le pr\u00e9sident de QIMC.\u201d<\/p>\n<p><img class=\"\\\"alignnone\" size-full wp-image-1215\\\" src=\"\\\"https:><\/p>\n<p>Figure 1 : Carte g\u00e9ographique simplifi\u00e9e centr\u00e9e sur le graben du Saguenay. Source : <a href=\"\/fr\/\"https:>https:\/\/toponymie.gouv.qc.ca\/ct\/ToposWeb\/fiche.aspx?no_seq=454187<\/a><\/p>\n<p>\u201c Le projet d\u2019exploration d\u2019hydrog\u00e8ne du Lac-Saint-Jean s\u2019inscrit dans la continuit\u00e9 logique des activit\u00e9s du QIMC au Qu\u00e9bec \u2019, a d\u00e9clar\u00e9 la professeure Richer-Lafl\u00e8che, directrice du Laboratoire de g\u00e9osciences appliqu\u00e9es de l\u2019INRS. \u201d D\u2019apr\u00e8s la compilation des donn\u00e9es g\u00e9oscientifiques et la comparaison du contexte g\u00e9ologique avec celui de la r\u00e9gion de T\u00e9miscamingue \u2019, pr\u00e9cise-t-elle, \u201c la r\u00e9gion du Saguenay\u2013Lac-Saint-Jean pourrait constituer un second graben sur un socle pr\u00e9cambrien, tr\u00e8s favorable \u00e0 la pr\u00e9sence d\u2019hydrog\u00e8ne blanc (naturel). \u201d<\/p>\n<p>\u201c G\u00e9ologiquement, le projet s\u2019inscrit dans le mod\u00e8le des grabens et rifts continentaux d\u00e9velopp\u00e9s sur un socle pr\u00e9cambrien, caract\u00e9ris\u00e9s par leur couverture de roches s\u00e9dimentaires pal\u00e9ozo\u00efques \u201d, poursuit le professeur Richer-Lafleche. \u201c Le graben du Saguenay, orient\u00e9 NO-SE, recoupe les roches pr\u00e9cambriennes de la province tectonique de Grenville sur une superficie de plus de 300 km sur 50 km, entre le nord-ouest du Saguenay\u2013Lac-Saint-Jean (secteur d\u2019Albanel) et Tadoussac. Ce graben est associ\u00e9 \u00e0 une importante d\u00e9pression topographique r\u00e9gionale, clairement visible sur les images lidar et satellitaires, et localement li\u00e9e au fjord du Saguenay (fig. 2). \u201d<\/p>\n<p><img class=\"\\\"alignnone\" size-full wp-image-1216\\\" src=\"\\\"https:><\/p>\n<p>Figure 2 : Images satellite topographiques de la r\u00e9gion de Saquenay\u2013Lac-Saint-Jean et du fjord de Saquenay montrant le graben de Saquenay. Source :<\/p>\n<p>https:\/\/publications.gc.ca\/collections\/collection_2022\/rncan-nrcan\/m183-2\/M183-2-8826-eng.pdf<\/p>\n<p>\u201c La zone tectonique du graben semble \u00eatre active depuis plus de 546 Ma, comme en t\u00e9moigne la mise en place d&#039;un magmatisme alcalin repr\u00e9sent\u00e9 r\u00e9gionalement par de nombreuses carbonatites (p. ex. la carbonatite de Saint-Honor\u00e9, mine de Niobec), mais aussi par des lamprophyres et des kimberlites (Gittins et al., 1975) \u201d, note le professeur Richer-Lafleche. \u201c Les failles normales du graben ont ensuite \u00e9t\u00e9 r\u00e9activ\u00e9es entre 200 et 250 Ma, au Trias et au Jurassique inf\u00e9rieur (Tremblay et al., 2013). Le graben pr\u00e9sente encore une activit\u00e9 n\u00e9otectonique, comme en t\u00e9moigne la magnitude du s\u00e9isme qui a frapp\u00e9 la r\u00e9gion du Saguenay\u2013Lac-Saint-Jean en 1988. \u2019 \u201d\u00a0De plus,\u00a0\u201c pr\u00e9cise le professeur Richer-Lafleche, \u201d\u00a0dans les parties ouest et sud-ouest du lac Saint-Jean, des failles normales de type graben recoupent d\u2019importants volumes de roches granitiques et sy\u00e9nitiques potassiques, ainsi que des roches intrusives mafiques associ\u00e9es au complexe anorthositique du lac Saint-Jean. Les roches potassiques, \u00e9galement riches en actinides, constituent des sources potentielles de production d\u2019hydrog\u00e8ne par des processus radiolytiques.\u00a0\u201c<\/p>\n<p>\u201c Le vaste environnement g\u00e9ologique de la r\u00e9gion est id\u00e9al pour l\u2019exploration de l\u2019hydrog\u00e8ne et de l\u2019h\u00e9lium \u201d, a d\u00e9clar\u00e9 John Karagiannidis, pr\u00e9sident de QIMC. \u201c Notre prochain programme d\u2019exploration d\u2019hydrog\u00e8ne naturel au lac Saint-Jean s\u2019inscrit parfaitement dans la mission de QIMC, qui est d\u2019appuyer les objectifs ambitieux du Qu\u00e9bec en mati\u00e8re d\u2019\u00e9nergie propre et de r\u00e9duction des \u00e9missions. En faisant progresser ce programme, nous r\u00e9affirmons notre engagement envers des solutions \u00e9nerg\u00e9tiques novatrices et durables et contribuons aux efforts de la province pour b\u00e2tir un avenir plus vert et plus durable. Nous avons h\u00e2te, comme \u00e0 Ville-Marie, de constater les retomb\u00e9es positives que nos initiatives en mati\u00e8re d\u2019hydrog\u00e8ne propre auront sur l\u2019\u00e9conomie locale du lac Saint-Jean. \u201d<\/p>\n<p>La coupe sch\u00e9matique de la figure 3 donne un aper\u00e7u de la g\u00e9ologie et de la topographie du graben du Saguenay.<\/p>\n<p><img class=\"\\\"alignnone\" size-full wp-image-1217\\\" src=\"\\\"https:><\/p>\n<p>Figure 3\u00a0: Coupe g\u00e9ologique simplifi\u00e9e du graben du Saguenay entre le parc des Laurentides et les monts Valins. Source\u00a0: https:\/\/eco-baleine.ca\/wp-content\/uploads\/2019\/06\/FORMATION-DU-FJORD-DU-SAGUENAY.pdf<\/p>\n<p>&nbsp;<\/p>\n<p>R\u00e9f\u00e9rences :<\/p>\n<p>Gittins,J., Hewins, RH, et\u2217,Laurin, AF, 1975. Dykes kimberlitiques-carbonatitiques de la vall\u00e9e de la rivi\u00e8re Saguenay, Qu\u00e9bec, Canada. Physique et chimie de la Terre. Volume 9, pages 137-148.<\/p>\n<p>Tremblay, A., Roden-Tice, M., Brandt, JA, Megan, TW, 2013. R\u00e9activation de failles m\u00e9sozo\u00efques le long du syst\u00e8me de rift du Saint-Laurent, dans l&#039;est du Canada : preuves thermochronologiques de la datation par traces de fission de l&#039;apatite. Bulletin of the Geological Society of America 125(5-6):794-810.<\/p>\n<p><strong>\u00c0 propos de l&#039;INRS et du Pr. <\/strong><strong>Marc Richer-LaFl\u00e8che, P.G\u00e9o.<\/strong><\/p>\n<p>L\u2019Institut national de la recherche scientifique (INRS) est un institut de recherche et de formation de haut niveau. L\u2019\u00e9quipe du Pr Richer-LaFl\u00e8che poss\u00e8de une expertise exceptionnelle en g\u00e9ologie, g\u00e9ochimie et g\u00e9ophysique, notamment dans les r\u00e9gions des concessions r\u00e9cemment acquises par QIMC. Elle a men\u00e9 plus de six ann\u00e9es de travaux g\u00e9ophysiques et g\u00e9ochimiques et r\u00e9alis\u00e9 des milliers d\u2019analyses de gaz du sol (C1-C4).<\/p>\n<ol>\n<li>Richer-LaFl\u00e8che d\u00e9tient \u00e9galement une subvention du FRQNT, en partenariat avec le R\u00e9seau des mines et de la g\u00e9ologie du Qu\u00e9bec et l\u2019industrie mini\u00e8re, pour d\u00e9velopper et optimiser une m\u00e9thode d\u2019analyse des gaz du sol permettant la d\u00e9tection directe des corps min\u00e9ralis\u00e9s et des failles sous la couverture quaternaire. Outre les gaz sulfur\u00e9s, l\u2019hydrog\u00e8ne a \u00e9t\u00e9 syst\u00e9matiquement analys\u00e9 lors des nombreuses campagnes de lev\u00e9s effectu\u00e9es en 2023 en Abitibi, \u00e0 T\u00e9miscamingue et dans les Appachies qu\u00e9b\u00e9coises. M. Richer-LaFl\u00e8che est la personne qualifi\u00e9e responsable de l\u2019information technique contenue dans ce communiqu\u00e9 et en a pris connaissance.<\/li>\n<\/ol>\n<p>De plus, l\u2019\u00e9quipe de l\u2019INRS dispose de plusieurs spectrom\u00e8tres \u00e0 gaz portables ainsi que du mat\u00e9riel d\u2019\u00e9chantillonnage et de la logistique n\u00e9cessaires pour pr\u00e9lever des \u00e9chantillons de gaz et effectuer des mesures g\u00e9ophysiques sur le terrain ou en milieu aquatique. Il est g\u00e9ologue professionnel, membre de l\u2019Ordre des g\u00e9ologues du Qu\u00e9bec et personne qualifi\u00e9e responsable de l\u2019information technique contenue dans ce communiqu\u00e9. Il a pris connaissance de l\u2019information qui y est pr\u00e9sent\u00e9e et approuve le communiqu\u00e9.<\/p>\n<p><strong>Engagement d&#039;une soci\u00e9t\u00e9 de relations investisseurs<\/strong><\/p>\n<p>QIMC annonce avoir retenu les services de German Mining Networks GmbH (\u201c\u00a0GMN\u00a0\u201d), soci\u00e9t\u00e9 de relations investisseurs situ\u00e9e \u00e0 Hauptstr. 82, 98593 Floh-Seligenthal, Allemagne, t\u00e9l.\u00a0: +49\u00a0176\u00a0990\u00a0960\u00a054, courriel\u00a0: krahp@german-mining.com, pour la prestation de services de relations investisseurs (les \u201c\u00a0Services\u00a0\u201d) \u00e0 la Soci\u00e9t\u00e9, sous r\u00e9serve de l\u2019approbation de la Bourse canadienne des valeurs mobili\u00e8res (\u201c\u00a0CSE\u00a0\u201d). Peter Krah est le directeur g\u00e9n\u00e9ral de GMN et sera responsable de l\u2019ensemble des Services rendus \u00e0 la Soci\u00e9t\u00e9.<\/p>\n<p>GMN assurera la cr\u00e9ation de vid\u00e9os de haute qualit\u00e9 sur QIMC via YouTube et la diffusion des informations via 400 agences de presse.<\/p>\n<p>GMN fournira les Services \u00e0 la Soci\u00e9t\u00e9 pour une p\u00e9riode de trois mois commen\u00e7ant le 11 septembre 2024 et se terminant le 11 novembre 2024. GMN recevra $28,500 en lien avec les Services.<\/p>\n<p>Ni GMN, ni Peter Krah ne d\u00e9tiennent actuellement d&#039;int\u00e9r\u00eat direct ou indirect dans les titres de la Soci\u00e9t\u00e9, ni n&#039;ont le droit ou l&#039;intention d&#039;en acqu\u00e9rir un. GMN et Peter Krah sont des entit\u00e9s ind\u00e9pendantes de la Soci\u00e9t\u00e9.<\/p>\n<p>Pour plus d&#039;informations sur la Soci\u00e9t\u00e9 des mat\u00e9riaux innovants du Qu\u00e9bec et ses produits, veuillez consulter le site Web suivant\u00a0: <a href=\"\/fr\/\"http:>www.qimaterials.com<\/a><\/p>\n<p><strong>\u00c0 propos de la Soci\u00e9t\u00e9 des mat\u00e9riaux innovants du Qu\u00e9bec.<\/strong><\/p>\n<p>Qu\u00e9bec Innovative Materials Corp. est une soci\u00e9t\u00e9 d&#039;exploration et de d\u00e9veloppement minier qui se consacre \u00e0 l&#039;exploration et \u00e0 l&#039;exploitation du potentiel des abondantes ressources du Canada. Poss\u00e9dant des propri\u00e9t\u00e9s en Ontario et au Qu\u00e9bec, QIMC se sp\u00e9cialise dans l&#039;exploration de gisements d&#039;hydrog\u00e8ne blanc (naturel) et de silice \u00e0 haute teneur. QIMC s&#039;engage \u00e0 adopter des pratiques durables et \u00e0 innover. Ax\u00e9e sur la g\u00e9rance environnementale et l&#039;utilisation de technologies d&#039;extraction de pointe, notre entreprise vise \u00e0 lib\u00e9rer tout le potentiel de ces mat\u00e9riaux afin de favoriser des solutions \u00e9nerg\u00e9tiques propres pour alimenter l&#039;intelligence artificielle et une \u00e9conomie carboneutre et contribuer \u00e0 un avenir plus durable.<\/p>\n<p><strong>QU\u00c9BEC MAT\u00c9RIAUX INNOVANTS CORP.<\/strong><\/p>\n<p>John Karagiannidis<\/p>\n<p>Directeur g\u00e9n\u00e9ral<\/p>\n<p>T\u00e9l. : +1 438-401-8271<\/p>\n<p>Pour plus d&#039;informations, veuillez contacter\u00a0:<\/p>\n<p>E-mail: <a href=\"\/fr\/\"mailto:info@qimaterials.com\\\"\">info@qimaterials.com <\/a><\/p>\n<p>Ni la Bourse canadienne des valeurs mobili\u00e8res ni son fournisseur de services de r\u00e9glementation (tel que ce terme est d\u00e9fini dans les politiques de la CSE) n&#039;acceptent la responsabilit\u00e9 de l&#039;ad\u00e9quation ou de l&#039;exactitude du pr\u00e9sent communiqu\u00e9 et n&#039;ont ni approuv\u00e9 ni d\u00e9sapprouv\u00e9 son contenu.<\/p>\n<p><strong>D\u00e9clarations prospectives<\/strong><\/p>\n<p><em>Ce communiqu\u00e9 contient des \u00e9nonc\u00e9s prospectifs. Ces \u00e9nonc\u00e9s prospectifs comportent des risques connus et inconnus, des incertitudes et d\u2019autres facteurs qui pourraient faire en sorte que les r\u00e9sultats, le rendement ou les r\u00e9alisations r\u00e9els de Qu\u00e9bec Mat\u00e9riaux Innovants, ou l\u2019\u00e9volution du secteur, diff\u00e8rent sensiblement des r\u00e9sultats, du rendement ou des r\u00e9alisations anticip\u00e9s, exprim\u00e9s ou sous-entendus par ces \u00e9nonc\u00e9s prospectifs. Les \u00e9nonc\u00e9s prospectifs ne constituent pas des faits historiques et sont g\u00e9n\u00e9ralement, mais pas toujours, identifi\u00e9s par des termes comme \u201d pr\u00e9voit \u201d, \u2019 planifie \u201d, \u201d anticipe \u201d, \u201d croit \u201d, \u201d a l\u2019intention de \u201d, \u201d estime \u201d, \u201d projette \u201d, \u201d potentiel \u201d et autres expressions similaires, ou par l\u2019emploi des verbes \u201d se r\u00e9aliser \u201d, \u201d pourrait se r\u00e9aliser \u201d, \u201d pourrait se r\u00e9aliser \u201d ou \u201d devrait se r\u00e9aliser \u201d.<\/em><\/p>\n<p><em>Bien que Qu\u00e9bec Mat\u00e9riaux Innovants estime que les informations prospectives contenues dans ce communiqu\u00e9 de presse soient raisonnables compte tenu des informations disponibles \u00e0 la date des pr\u00e9sentes, de par leur nature, les \u00e9nonc\u00e9s prospectifs comportent des hypoth\u00e8ses, des risques connus et inconnus, des incertitudes et d\u2019autres facteurs qui pourraient faire en sorte que nos r\u00e9sultats, notre rendement ou nos r\u00e9alisations r\u00e9els, ou d\u2019autres \u00e9v\u00e9nements futurs, diff\u00e8rent sensiblement des r\u00e9sultats, du rendement ou des r\u00e9alisations futurs exprim\u00e9s ou sous-entendus par ces \u00e9nonc\u00e9s prospectifs.<\/em><\/p>\n<p><em>Ces hypoth\u00e8ses, risques et incertitudes comprennent, sans toutefois s&#039;y limiter, ceux li\u00e9s \u00e0 la conjoncture \u00e9conomique g\u00e9n\u00e9rale; aux \u00e9v\u00e9nements d\u00e9favorables touchant l&#039;industrie; \u00e0 l&#039;\u00e9volution future de la l\u00e9gislation et de la r\u00e9glementation dans le secteur minier; \u00e0 la capacit\u00e9 de la Soci\u00e9t\u00e9 d&#039;obtenir des capitaux suffisants de sources internes et externes, ou \u00e0 son incapacit\u00e9 d&#039;obtenir des capitaux suffisants \u00e0 des conditions favorables; \u00e0 l&#039;industrie et aux march\u00e9s miniers au Canada et en g\u00e9n\u00e9ral; \u00e0 la capacit\u00e9 de Qu\u00e9bec Mat\u00e9riaux Innovants Corp. de mettre en \u0153uvre ses strat\u00e9gies commerciales; \u00e0 la concurrence; et \u00e0 d&#039;autres hypoth\u00e8ses, risques et incertitudes.<\/em><\/p>\n<p><em>Les informations prospectives contenues dans ce communiqu\u00e9 de presse refl\u00e8tent les attentes de la Soci\u00e9t\u00e9 \u00e0 la date de publication et sont donc susceptibles d&#039;\u00e9voluer. Les lecteurs ne doivent pas accorder une importance excessive \u00e0 ces informations prospectives et ne doivent pas s&#039;y fier \u00e0 une date ult\u00e9rieure. Bien que la Soci\u00e9t\u00e9 puisse choisir de le faire, elle ne s&#039;engage pas \u00e0 mettre \u00e0 jour ces informations \u00e0 un moment pr\u00e9cis, sauf si la loi l&#039;exige.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Lachute, Quebec, September 11, 2024\u00a0 Quebec Innovative Materials Corp. (CSE: QIMC, FSE: 7FJ) (\u201cQI Materials\u201d, \u201cQIMC\u201d or the \u201cCompany\u201d)\u2013 \u00a0QIMC is pleased to announce the successful exercise of 9.915 million warrants, marking another significant advancement in our hydrogen initiatives. \u201cThis achievement underscores our shareholders\\&#8217; strong confidence in our mission and strategy.\u201d said John Karagiannidis, president [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":978,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","iawp_total_views":2,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-1213","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press-releases"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>QIMC Announces Successful Exercise of Warrants and Strategic Advances in Fully Funded Hydrogen Exploration Program - QIMC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/qimaterials.com\/fr\/qimc-announces-successful-exercise-of-warrants-and-strategic-advances-in-fully-funded-hydrogen-exploration-program\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"QIMC Announces Successful Exercise of Warrants and Strategic Advances in Fully Funded Hydrogen Exploration Program - QIMC\" \/>\n<meta property=\"og:description\" content=\"Lachute, Quebec, September 11, 2024\u00a0 Quebec Innovative Materials Corp. (CSE: QIMC, FSE: 7FJ) (\u201cQI Materials\u201d, \u201cQIMC\u201d or the \u201cCompany\u201d)\u2013 \u00a0QIMC is pleased to announce the successful exercise of 9.915 million warrants, marking another significant advancement in our hydrogen initiatives. \u201cThis achievement underscores our shareholders&#8217; strong confidence in our mission and strategy.\u201d said John Karagiannidis, president [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/qimaterials.com\/fr\/qimc-announces-successful-exercise-of-warrants-and-strategic-advances-in-fully-funded-hydrogen-exploration-program\/\" \/>\n<meta property=\"og:site_name\" content=\"QIMC\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-11T12:36:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-14T15:27:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/qimaterials.com\/wp-content\/uploads\/2024\/07\/newpos2-min.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"QIMC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"QIMC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/qimaterials.com\\\/qimc-announces-successful-exercise-of-warrants-and-strategic-advances-in-fully-funded-hydrogen-exploration-program\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/qimaterials.com\\\/qimc-announces-successful-exercise-of-warrants-and-strategic-advances-in-fully-funded-hydrogen-exploration-program\\\/\"},\"author\":{\"name\":\"QIMC\",\"@id\":\"https:\\\/\\\/qimaterials.com\\\/#\\\/schema\\\/person\\\/39435340349b65729b1463189bf3d52e\"},\"headline\":\"QIMC Announces Successful Exercise of Warrants and Strategic Advances in Fully Funded Hydrogen Exploration Program\",\"datePublished\":\"2024-09-11T12:36:59+00:00\",\"dateModified\":\"2026-05-14T15:27:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/qimaterials.com\\\/qimc-announces-successful-exercise-of-warrants-and-strategic-advances-in-fully-funded-hydrogen-exploration-program\\\/\"},\"wordCount\":1824,\"image\":{\"@id\":\"https:\\\/\\\/qimaterials.com\\\/qimc-announces-successful-exercise-of-warrants-and-strategic-advances-in-fully-funded-hydrogen-exploration-program\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/qimaterials.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/newpos2-min.jpg\",\"articleSection\":[\"Press Releases\"],\"inLanguage\":\"fr-CA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/qimaterials.com\\\/qimc-announces-successful-exercise-of-warrants-and-strategic-advances-in-fully-funded-hydrogen-exploration-program\\\/\",\"url\":\"https:\\\/\\\/qimaterials.com\\\/qimc-announces-successful-exercise-of-warrants-and-strategic-advances-in-fully-funded-hydrogen-exploration-program\\\/\",\"name\":\"QIMC Announces Successful Exercise of Warrants and Strategic Advances in Fully Funded Hydrogen Exploration Program - QIMC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/qimaterials.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/qimaterials.com\\\/qimc-announces-successful-exercise-of-warrants-and-strategic-advances-in-fully-funded-hydrogen-exploration-program\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/qimaterials.com\\\/qimc-announces-successful-exercise-of-warrants-and-strategic-advances-in-fully-funded-hydrogen-exploration-program\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/qimaterials.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/newpos2-min.jpg\",\"datePublished\":\"2024-09-11T12:36:59+00:00\",\"dateModified\":\"2026-05-14T15:27:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/qimaterials.com\\\/#\\\/schema\\\/person\\\/39435340349b65729b1463189bf3d52e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/qimaterials.com\\\/qimc-announces-successful-exercise-of-warrants-and-strategic-advances-in-fully-funded-hydrogen-exploration-program\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/qimaterials.com\\\/qimc-announces-successful-exercise-of-warrants-and-strategic-advances-in-fully-funded-hydrogen-exploration-program\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/qimaterials.com\\\/qimc-announces-successful-exercise-of-warrants-and-strategic-advances-in-fully-funded-hydrogen-exploration-program\\\/#primaryimage\",\"url\":\"https:\\\/\\\/qimaterials.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/newpos2-min.jpg\",\"contentUrl\":\"https:\\\/\\\/qimaterials.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/newpos2-min.jpg\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/qimaterials.com\\\/qimc-announces-successful-exercise-of-warrants-and-strategic-advances-in-fully-funded-hydrogen-exploration-program\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/qimaterials.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"QIMC Announces Successful Exercise of Warrants and Strategic Advances in Fully Funded Hydrogen Exploration Program\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/qimaterials.com\\\/#website\",\"url\":\"https:\\\/\\\/qimaterials.com\\\/\",\"name\":\"QIMC\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/qimaterials.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/qimaterials.com\\\/#\\\/schema\\\/person\\\/39435340349b65729b1463189bf3d52e\",\"name\":\"QIMC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/be8e855ddb2feed9f69b34fe07d3bbe8170061f3d521894bb1b409ca52c7d750?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/be8e855ddb2feed9f69b34fe07d3bbe8170061f3d521894bb1b409ca52c7d750?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/be8e855ddb2feed9f69b34fe07d3bbe8170061f3d521894bb1b409ca52c7d750?s=96&d=mm&r=g\",\"caption\":\"QIMC\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"QIMC annonce le succ\u00e8s de l&#039;exercice de ses bons de souscription et des avanc\u00e9es strat\u00e9giques dans son programme d&#039;exploration d&#039;hydrog\u00e8ne enti\u00e8rement financ\u00e9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/qimaterials.com\/fr\/qimc-announces-successful-exercise-of-warrants-and-strategic-advances-in-fully-funded-hydrogen-exploration-program\/","og_locale":"fr_CA","og_type":"article","og_title":"QIMC Announces Successful Exercise of Warrants and Strategic Advances in Fully Funded Hydrogen Exploration Program - QIMC","og_description":"Lachute, Quebec, September 11, 2024\u00a0 Quebec Innovative Materials Corp. (CSE: QIMC, FSE: 7FJ) (\u201cQI Materials\u201d, \u201cQIMC\u201d or the \u201cCompany\u201d)\u2013 \u00a0QIMC is pleased to announce the successful exercise of 9.915 million warrants, marking another significant advancement in our hydrogen initiatives. \u201cThis achievement underscores our shareholders&#8217; strong confidence in our mission and strategy.\u201d said John Karagiannidis, president [&hellip;]","og_url":"https:\/\/qimaterials.com\/fr\/qimc-announces-successful-exercise-of-warrants-and-strategic-advances-in-fully-funded-hydrogen-exploration-program\/","og_site_name":"QIMC","article_published_time":"2024-09-11T12:36:59+00:00","article_modified_time":"2026-05-14T15:27:43+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/qimaterials.com\/wp-content\/uploads\/2024\/07\/newpos2-min.jpg","type":"image\/jpeg"}],"author":"QIMC","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"QIMC","Estimation du temps de lecture":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/qimaterials.com\/qimc-announces-successful-exercise-of-warrants-and-strategic-advances-in-fully-funded-hydrogen-exploration-program\/#article","isPartOf":{"@id":"https:\/\/qimaterials.com\/qimc-announces-successful-exercise-of-warrants-and-strategic-advances-in-fully-funded-hydrogen-exploration-program\/"},"author":{"name":"QIMC","@id":"https:\/\/qimaterials.com\/#\/schema\/person\/39435340349b65729b1463189bf3d52e"},"headline":"QIMC Announces Successful Exercise of Warrants and Strategic Advances in Fully Funded Hydrogen Exploration Program","datePublished":"2024-09-11T12:36:59+00:00","dateModified":"2026-05-14T15:27:43+00:00","mainEntityOfPage":{"@id":"https:\/\/qimaterials.com\/qimc-announces-successful-exercise-of-warrants-and-strategic-advances-in-fully-funded-hydrogen-exploration-program\/"},"wordCount":1824,"image":{"@id":"https:\/\/qimaterials.com\/qimc-announces-successful-exercise-of-warrants-and-strategic-advances-in-fully-funded-hydrogen-exploration-program\/#primaryimage"},"thumbnailUrl":"https:\/\/qimaterials.com\/wp-content\/uploads\/2024\/07\/newpos2-min.jpg","articleSection":["Press Releases"],"inLanguage":"fr-CA"},{"@type":"WebPage","@id":"https:\/\/qimaterials.com\/qimc-announces-successful-exercise-of-warrants-and-strategic-advances-in-fully-funded-hydrogen-exploration-program\/","url":"https:\/\/qimaterials.com\/qimc-announces-successful-exercise-of-warrants-and-strategic-advances-in-fully-funded-hydrogen-exploration-program\/","name":"QIMC annonce le succ\u00e8s de l&#039;exercice de ses bons de souscription et des avanc\u00e9es strat\u00e9giques dans son programme d&#039;exploration d&#039;hydrog\u00e8ne enti\u00e8rement financ\u00e9.","isPartOf":{"@id":"https:\/\/qimaterials.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/qimaterials.com\/qimc-announces-successful-exercise-of-warrants-and-strategic-advances-in-fully-funded-hydrogen-exploration-program\/#primaryimage"},"image":{"@id":"https:\/\/qimaterials.com\/qimc-announces-successful-exercise-of-warrants-and-strategic-advances-in-fully-funded-hydrogen-exploration-program\/#primaryimage"},"thumbnailUrl":"https:\/\/qimaterials.com\/wp-content\/uploads\/2024\/07\/newpos2-min.jpg","datePublished":"2024-09-11T12:36:59+00:00","dateModified":"2026-05-14T15:27:43+00:00","author":{"@id":"https:\/\/qimaterials.com\/#\/schema\/person\/39435340349b65729b1463189bf3d52e"},"breadcrumb":{"@id":"https:\/\/qimaterials.com\/qimc-announces-successful-exercise-of-warrants-and-strategic-advances-in-fully-funded-hydrogen-exploration-program\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/qimaterials.com\/qimc-announces-successful-exercise-of-warrants-and-strategic-advances-in-fully-funded-hydrogen-exploration-program\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/qimaterials.com\/qimc-announces-successful-exercise-of-warrants-and-strategic-advances-in-fully-funded-hydrogen-exploration-program\/#primaryimage","url":"https:\/\/qimaterials.com\/wp-content\/uploads\/2024\/07\/newpos2-min.jpg","contentUrl":"https:\/\/qimaterials.com\/wp-content\/uploads\/2024\/07\/newpos2-min.jpg","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/qimaterials.com\/qimc-announces-successful-exercise-of-warrants-and-strategic-advances-in-fully-funded-hydrogen-exploration-program\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/qimaterials.com\/"},{"@type":"ListItem","position":2,"name":"QIMC Announces Successful Exercise of Warrants and Strategic Advances in Fully Funded Hydrogen Exploration Program"}]},{"@type":"WebSite","@id":"https:\/\/qimaterials.com\/#website","url":"https:\/\/qimaterials.com\/","name":"QIMC","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/qimaterials.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Person","@id":"https:\/\/qimaterials.com\/#\/schema\/person\/39435340349b65729b1463189bf3d52e","name":"QIMC","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/be8e855ddb2feed9f69b34fe07d3bbe8170061f3d521894bb1b409ca52c7d750?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/be8e855ddb2feed9f69b34fe07d3bbe8170061f3d521894bb1b409ca52c7d750?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/be8e855ddb2feed9f69b34fe07d3bbe8170061f3d521894bb1b409ca52c7d750?s=96&d=mm&r=g","caption":"QIMC"}}]}},"_links":{"self":[{"href":"https:\/\/qimaterials.com\/fr\/wp-json\/wp\/v2\/posts\/1213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/qimaterials.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/qimaterials.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/qimaterials.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/qimaterials.com\/fr\/wp-json\/wp\/v2\/comments?post=1213"}],"version-history":[{"count":1,"href":"https:\/\/qimaterials.com\/fr\/wp-json\/wp\/v2\/posts\/1213\/revisions"}],"predecessor-version":[{"id":83574,"href":"https:\/\/qimaterials.com\/fr\/wp-json\/wp\/v2\/posts\/1213\/revisions\/83574"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/qimaterials.com\/fr\/wp-json\/wp\/v2\/media\/978"}],"wp:attachment":[{"href":"https:\/\/qimaterials.com\/fr\/wp-json\/wp\/v2\/media?parent=1213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/qimaterials.com\/fr\/wp-json\/wp\/v2\/categories?post=1213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/qimaterials.com\/fr\/wp-json\/wp\/v2\/tags?post=1213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}